

{"id":306,"date":"2022-08-15T14:42:32","date_gmt":"2022-08-15T14:42:32","guid":{"rendered":"http:\/\/localhost:10048\/?page_id=306"},"modified":"2026-06-05T09:54:14","modified_gmt":"2026-06-05T14:54:14","slug":"about","status":"publish","type":"page","link":"https:\/\/www.zinpro.com\/es_mx\/about\/","title":{"rendered":"Acerca de"},"content":{"rendered":"<div class=\"wp-block-cover alignfull is-light is-style-default\"><img loading=\"lazy\" decoding=\"async\" width=\"2400\" height=\"869\" class=\"wp-block-cover__image-background wp-image-48106\" alt=\"\" src=\"http:\/\/www.zinpro.com\/wp-content\/uploads\/2023\/04\/AboutHero.jpg\" style=\"object-position:51% 9%\" data-object-fit=\"cover\" data-object-position=\"51% 9%\" srcset=\"https:\/\/www.zinpro.com\/wp-content\/uploads\/2023\/04\/AboutHero.jpg 2400w, https:\/\/www.zinpro.com\/wp-content\/uploads\/2023\/04\/AboutHero-300x109.jpg 300w, https:\/\/www.zinpro.com\/wp-content\/uploads\/2023\/04\/AboutHero-1024x371.jpg 1024w, https:\/\/www.zinpro.com\/wp-content\/uploads\/2023\/04\/AboutHero-1600x579.jpg 1600w, https:\/\/www.zinpro.com\/wp-content\/uploads\/2023\/04\/AboutHero-1536x556.jpg 1536w, https:\/\/www.zinpro.com\/wp-content\/uploads\/2023\/04\/AboutHero-2048x742.jpg 2048w, https:\/\/www.zinpro.com\/wp-content\/uploads\/2023\/04\/AboutHero-18x7.jpg 18w\" sizes=\"auto, (max-width: 2400px) 100vw, 2400px\" \/><span aria-hidden=\"true\" class=\"wp-block-cover__background has-background-dim-10 has-background-dim\"><\/span><div class=\"wp-block-cover__inner-container is-layout-flow wp-block-cover-is-layout-flow\">\n<h1 class=\"wp-block-heading has-text-align-left has-white-color has-text-color\" id=\"h-about-zinpro-corporation\">Acerca de Zinpro\u00ae Corporation<\/h1>\n<\/div><\/div>\n\n\n\n\n<div id=\"resp-spacer-block_760b1e38835868b90d8cb78b8b586898\" class=\"zinpro-spacer-block\"><\/div>\n\n<style>\n#resp-spacer-block_760b1e38835868b90d8cb78b8b586898 {\n\tmargin-top: 80px;\n}\n\n@media screen and (max-width: 1366px) {\n\t#resp-spacer-block_760b1e38835868b90d8cb78b8b586898 {\n\t\tmargin-top: 60px;\n\t}\n}\n\n@media screen and (max-width: 960px) {\n\t#resp-spacer-block_760b1e38835868b90d8cb78b8b586898 {\n\t\tmargin-top: 40px;\n\t}\n}\n<\/style>\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-vertically-aligned-center wow fadeInUp is-layout-flow wp-block-column-is-layout-flow\">\n<p class=\"wp-block-paragraph\">Durante m\u00e1s de 50 a\u00f1os, Zinpro ha mejorado la salud y el bienestar de animales y personas como pionera en la investigaci\u00f3n y el desarrollo de oligoelementos de alto rendimiento y soluciones nutricionales innovadoras. Como empresa familiar de capital privado, nuestro crecimiento constante puede atribuirse al empleo de un equipo de expertos de talla mundial, a la fabricaci\u00f3n de productos de calidad y a nuestro firme compromiso de ayudar a nuestros clientes a mejorar la salud y el rendimiento de sus animales. Con productos comercializados en m\u00e1s de 70 pa\u00edses de todo el mundo, Zinpro es el l\u00edder mundial en la mejora del rendimiento animal a trav\u00e9s de una mejor nutrici\u00f3n y se dedica a crear pr\u00e1cticas m\u00e1s inteligentes para un mundo mejor y m\u00e1s sostenible.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column wow fadeInUp anim-delay-300ms is-layout-flow wp-block-column-is-layout-flow\"><div class=\"epyt-video-wrapper\"><div  id=\"_ytid_70047\"  width=\"800\" height=\"450\"  data-origwidth=\"800\" data-origheight=\"450\" data-facadesrc=\"https:\/\/www.youtube.com\/embed\/XWkNHeZiOGE?enablejsapi=1&#038;autoplay=0&#038;cc_load_policy=0&#038;cc_lang_pref=&#038;iv_load_policy=1&#038;loop=0&#038;rel=0&#038;fs=0&#038;playsinline=1&#038;autohide=2&#038;theme=dark&#038;color=red&#038;controls=1&#038;disablekb=0&#038;\" class=\"__youtube_prefs__ epyt-facade no-lazyload\" data-epautoplay=\"1\" ><img decoding=\"async\" data-spai-excluded=\"true\" class=\"epyt-facade-poster skip-lazy\" loading=\"lazy\"  alt=\"YouTube player\"  src=\"https:\/\/i.ytimg.com\/vi\/XWkNHeZiOGE\/hqdefault.jpg\"  \/><button class=\"epyt-facade-play\" aria-label=\"Jugar\"><svg data-no-lazy=\"1\" height=\"100%\" version=\"1.1\" viewbox=\"0 0 68 48\" width=\"100%\"><path class=\"ytp-large-play-button-bg\" d=\"M66.52,7.74c-0.78-2.93-2.49-5.41-5.42-6.19C55.79,.13,34,0,34,0S12.21,.13,6.9,1.55 C3.97,2.33,2.27,4.81,1.48,7.74C0.06,13.05,0,24,0,24s0.06,10.95,1.48,16.26c0.78,2.93,2.49,5.41,5.42,6.19 C12.21,47.87,34,48,34,48s21.79-0.13,27.1-1.55c2.93-0.78,4.64-3.26,5.42-6.19C67.94,34.95,68,24,68,24S67.94,13.05,66.52,7.74z\" fill=\"#f00\"><\/path><path d=\"M 45,24 27,14 27,34\" fill=\"#fff\"><\/path><\/svg><\/button><\/div><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><div id=\"gutenslider-9z9yoywi3\" class=\"wp-block-eedee-block-gutenslider gs-frontend content-fixed alignnone arrow-style-1 arrow-position-sides arrow-mb-none arrows-lg-none arrows-md-none arrows-sm-none dot-style-1 dots-lg dots-md dots-sm dot-position-bottom wow fadeInUp anim-delay-300ms is-position-center-center mb-none wrap-auto-height\" style=\"--gutenslider-min-height: 579px;--gutenslider-arrow-size: 30px;--gutenslider-dot-size: 25px;--gutenslider-arrow-color: #ffffff;--gutenslider-dot-color: #000000;--gutenslider-padding-y-mobile: 40px;--gutenslider-padding-x-mobile: 40px;--gutenslider-padding-y-tablet: 40px;--gutenslider-padding-x-tablet: 40px;--gutenslider-padding-y-desktop: 40px;--gutenslider-padding-x-desktop: 40px;--gutenslider-bg-image: url();--gutenslider-min-height-md: 50vh;--gutenslider-min-height-sm: 50vh;--gutenslider-padding-x: 87px;--gutenslider-padding-x-md: 87px;--gutenslider-padding-x-sm: 87px;--gutenslider-padding-y: 100px;--gutenslider-padding-y-md: 100px;--gutenslider-padding-y-sm: 100px;--gutenslider-arrow-size-md: 30px;--gutenslider-arrow-size-sm: 30px;--gutenslider-dot-size-md: 25px;--gutenslider-dot-size-sm: 25px;--gutenslider-arrow-bg-color: transparent;--gutenslider-arrow-hover-color: #eeeeee;--gutenslider-arrow-bg-hover-color: transparent;--gutenslider-arrow-x-offset: 10px;--gutenslider-arrow-x-offset-md: 10px;--gutenslider-arrow-x-offset-sm: 10px;--gutenslider-arrow-y-offset: 0px;--gutenslider-arrow-y-offset-md: 0px;--gutenslider-arrow-y-offset-sm: 0px;--gutenslider-arrow-x-spacing: 0px;--gutenslider-dot-y-offset: -37px;--gutenslider-dot-y-offset-md: -37px;--gutenslider-dot-y-offset-sm: -37px;--gutenslider-margin-x: 51px;--gutenslider-margin-x-md: 51px;--gutenslider-margin-x-sm: 51px;--gutenslider-margin-y: 50px;--gutenslider-margin-y-md: 50px;--gutenslider-margin-y-sm: 50px;--gutenslider-divider-top: 60px;--gutenslider-divider-bottom: 60px;--gutenslider-lightgallery-bg: #ffffff;--gutenslider-lightgallery-font: #000000;--gs-first-pos: 49% 50%;--gs-gap-vertical: var( --wp--style--gallery-gap-default, var( --gallery-block--gutter-size, var( --wp--style--block-gap, 0.5em ) ) );--gs-gap-horizontal: var( --wp--style--gallery-gap-default, var( --gallery-block--gutter-size, var( --wp--style--block-gap, 0.5em ) ) );\" data-parallax-direction=\"down\" data-parallax-amount=\"1.3\" data-lg-transition=\"lg-slide\" data-hash=\"\"><div class=\"eedee-swiper-outer\"><div class=\"gutenslider-divider-top\" style=\"color:#fff;\"><\/div><div class=\"swiper\" data-settings='{\"autoplay\":{\"delay\":4000,\"pauseOnMouseEnter\":true,\"disableOnInteraction\":false},\"speed\":700,\"direction\":\"horizontal\",\"autoHeight\":\"\",\"loop\":false,\"centeredSlides\":true,\"spaceBetween\":0,\"slidesPerView\":1,\"slidesPerGroup\":1,\"effect\":\"slide\",\"coverflowEffect\":{\"rotate\":30,\"slideShadows\":false,\"depth\":100,\"stretch\":50,\"modifier\":1},\"fadeEffect\":{\"crossFade\":true},\"zoom\":\"\",\"navigation\":{\"nextEl\":\"#gutenslider-9z9yoywi3 .eedee-gutenslider-next\",\"prevEl\":\"#gutenslider-9z9yoywi3 .eedee-gutenslider-prev\"},\"pagination\":{\"type\":\"bullets\",\"clickable\":true,\"dynamicBullets\":false,\"el\":\"#gutenslider-9z9yoywi3 .eedee-gutenslider-pagination\"},\"pauseOnHover\":\"1\",\"watchSlidesProgress\":true,\"watchSlidesVisibility\":true,\"settingsMd\":{\"autoHeight\":\"\",\"slidesPerView\":1,\"slidesPerGroup\":1,\"spaceBetween\":0,\"loop\":false},\"settingsLg\":{\"autoHeight\":\"\",\"slidesPerView\":1,\"slidesPerGroup\":1,\"spaceBetween\":0,\"loop\":false},\"hasLg\":false,\"hasLgCounter\":true,\"isFullScreen\":false,\"arrowsFollowMouse\":false,\"lgTitle\":\"none\",\"lgCaption\":\"none\",\"lgThumbnails\":true,\"lgZoomEnabled\":false,\"keyboard\":{\"keyboard\":{\"enabled\":true,\"onlyInViewport\":true}},\"hashNavigation\":false,\"dividers\":false}'><div class=\"swiper-wrapper\">\n<div class=\"swiper-slide wp-block-eedee-block-gutenslide is-position-center-center ed-bg-image\" style=\"--ed-vw:296;--ed-vh:300;\" data-hash=\"\"><div class=\"eedee-background-div bg-image\"><img loading=\"lazy\" width=\"500\" height=\"506\" class=\"wp-image-72440\" src=\"https:\/\/www.zinpro.com\/wp-content\/uploads\/2026\/02\/400_PeerReview_Logo-1.jpg\" alt=\"\" decoding=\"async\" style=\"object-fit: contain; object-position: 49% 50%;\"  data-title=\"400_PeerReview_Logo\" srcset=\"https:\/\/www.zinpro.com\/wp-content\/uploads\/2026\/02\/400_PeerReview_Logo-1.jpg 500w, https:\/\/www.zinpro.com\/wp-content\/uploads\/2026\/02\/400_PeerReview_Logo-1-296x300.jpg 296w, https:\/\/www.zinpro.com\/wp-content\/uploads\/2026\/02\/400_PeerReview_Logo-1-50x51.jpg 50w, https:\/\/www.zinpro.com\/wp-content\/uploads\/2026\/02\/400_PeerReview_Logo-1-12x12.jpg 12w, https:\/\/www.zinpro.com\/wp-content\/uploads\/2026\/02\/400_PeerReview_Logo-1-24x24.jpg 24w, https:\/\/www.zinpro.com\/wp-content\/uploads\/2026\/02\/400_PeerReview_Logo-1-36x36.jpg 36w, https:\/\/www.zinpro.com\/wp-content\/uploads\/2026\/02\/400_PeerReview_Logo-1-48x48.jpg 48w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><div class=\"eedee-background-div__overlay\" style=\"opacity:1;\"><\/div><\/div><div class=\"slide-content\">\n\n<div class=\"wp-block-uagb-image uagb-block-8e11d08f wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><img decoding=\"async\" src=\"https:\/\/www.zinpro.com\/wp-content\/uploads\/2026\/02\/400_PeerReview_Logo-1.jpg\" alt=\"\" class=\"uag-image-72440\" width=\"500\" height=\"349\" title=\"400_Revisi\u00f3n por pares_Logotipo\" loading=\"lazy\" role=\"img\" \/><\/figure><\/div>\n\n<\/div><\/div>\n\n<div class=\"swiper-slide wp-block-eedee-block-gutenslide is-position-center-center ed-bg-image\" style=\"--ed-vw:300;--ed-vh:300;\" data-hash=\"\"><div class=\"eedee-background-div bg-image\"><img loading=\"lazy\" width=\"578\" height=\"579\" class=\"wp-image-74028\" src=\"https:\/\/www.zinpro.com\/wp-content\/uploads\/2026\/06\/AboutZinpro-55Years.png\" alt=\"\" decoding=\"async\" style=\"object-fit: cover; object-position: 72% 56%;\"  data-title=\"AboutZinpro-55Years\" srcset=\"https:\/\/www.zinpro.com\/wp-content\/uploads\/2026\/06\/AboutZinpro-55Years.png 578w, https:\/\/www.zinpro.com\/wp-content\/uploads\/2026\/06\/AboutZinpro-55Years-300x300.png 300w, https:\/\/www.zinpro.com\/wp-content\/uploads\/2026\/06\/AboutZinpro-55Years-150x150.png 150w, https:\/\/www.zinpro.com\/wp-content\/uploads\/2026\/06\/AboutZinpro-55Years-50x50.png 50w, https:\/\/www.zinpro.com\/wp-content\/uploads\/2026\/06\/AboutZinpro-55Years-12x12.png 12w, https:\/\/www.zinpro.com\/wp-content\/uploads\/2026\/06\/AboutZinpro-55Years-24x24.png 24w, https:\/\/www.zinpro.com\/wp-content\/uploads\/2026\/06\/AboutZinpro-55Years-36x36.png 36w, https:\/\/www.zinpro.com\/wp-content\/uploads\/2026\/06\/AboutZinpro-55Years-48x48.png 48w\" sizes=\"auto, (max-width: 578px) 100vw, 578px\" \/><div class=\"eedee-background-div__overlay\" style=\"opacity:1;\"><\/div><\/div><div class=\"slide-content\">\n\n<p class=\"has-text-align-center gutenslider-content-initial has-larger-font-size wp-block-paragraph\"><\/p>\n\n<\/div><\/div>\n\n<div class=\"swiper-slide wp-block-eedee-block-gutenslide is-position-center-center ed-bg-image\" style=\"--ed-vw:263;--ed-vh:300;\" data-hash=\"\"><div class=\"eedee-background-div bg-image\"><img loading=\"lazy\" width=\"560\" height=\"640\" class=\"wp-image-48080\" src=\"http:\/\/www.zinpro.com\/wp-content\/uploads\/2023\/04\/AboutZinpro-70Countries-560x640-1.png\" alt=\"\" decoding=\"async\" style=\"object-fit: cover; object-position: 50% 50%;\"  data-title=\"AboutZinpro-70Countries-560x640-1\" srcset=\"https:\/\/www.zinpro.com\/wp-content\/uploads\/2023\/04\/AboutZinpro-70Countries-560x640-1.png 560w, https:\/\/www.zinpro.com\/wp-content\/uploads\/2023\/04\/AboutZinpro-70Countries-560x640-1-263x300.png 263w, https:\/\/www.zinpro.com\/wp-content\/uploads\/2023\/04\/AboutZinpro-70Countries-560x640-1-11x12.png 11w\" sizes=\"auto, (max-width: 560px) 100vw, 560px\" \/><div class=\"eedee-background-div__overlay\" style=\"opacity:1;\"><\/div><\/div><div class=\"slide-content\">\n\n<p class=\"has-text-align-center gutenslider-content-initial has-larger-font-size wp-block-paragraph\"><\/p>\n\n<\/div><\/div>\n\n<div class=\"swiper-slide wp-block-eedee-block-gutenslide is-position-center-center ed-bg-image\" style=\"--ed-vw:263;--ed-vh:300;\" data-hash=\"\"><div class=\"eedee-background-div bg-image\"><img loading=\"lazy\" width=\"560\" height=\"640\" class=\"wp-image-48081\" src=\"http:\/\/www.zinpro.com\/wp-content\/uploads\/2023\/04\/AboutZinpro-500Patents-560x640-1.png\" alt=\"\" decoding=\"async\" style=\"object-fit: cover; object-position: 50% 50%;\"  data-title=\"AboutZinpro-500Patents-560x640-1\" srcset=\"https:\/\/www.zinpro.com\/wp-content\/uploads\/2023\/04\/AboutZinpro-500Patents-560x640-1.png 560w, https:\/\/www.zinpro.com\/wp-content\/uploads\/2023\/04\/AboutZinpro-500Patents-560x640-1-263x300.png 263w, https:\/\/www.zinpro.com\/wp-content\/uploads\/2023\/04\/AboutZinpro-500Patents-560x640-1-11x12.png 11w\" sizes=\"auto, (max-width: 560px) 100vw, 560px\" \/><div class=\"eedee-background-div__overlay\" style=\"opacity:1;\"><\/div><\/div><div class=\"slide-content\">\n\n<p class=\"has-text-align-center gutenslider-content-initial has-larger-font-size wp-block-paragraph\"><\/p>\n\n<\/div><\/div>\n<\/div><\/div><div class=\"wp-block-eedee-gutenslider__content co-1\">\n<div class=\"swiper-slide wp-block-eedee-block-gutenslide is-position-center-center ed-bg-image\" style=\"--ed-vw:296;--ed-vh:300;\" data-hash=\"\"><div class=\"eedee-background-div bg-image\"><img loading=\"lazy\" width=\"500\" height=\"506\" class=\"wp-image-72440\" src=\"https:\/\/www.zinpro.com\/wp-content\/uploads\/2026\/02\/400_PeerReview_Logo-1.jpg\" alt=\"\" decoding=\"async\" style=\"object-fit: contain; object-position: 49% 50%;\"  data-title=\"400_PeerReview_Logo\" srcset=\"https:\/\/www.zinpro.com\/wp-content\/uploads\/2026\/02\/400_PeerReview_Logo-1.jpg 500w, https:\/\/www.zinpro.com\/wp-content\/uploads\/2026\/02\/400_PeerReview_Logo-1-296x300.jpg 296w, https:\/\/www.zinpro.com\/wp-content\/uploads\/2026\/02\/400_PeerReview_Logo-1-50x51.jpg 50w, https:\/\/www.zinpro.com\/wp-content\/uploads\/2026\/02\/400_PeerReview_Logo-1-12x12.jpg 12w, https:\/\/www.zinpro.com\/wp-content\/uploads\/2026\/02\/400_PeerReview_Logo-1-24x24.jpg 24w, https:\/\/www.zinpro.com\/wp-content\/uploads\/2026\/02\/400_PeerReview_Logo-1-36x36.jpg 36w, https:\/\/www.zinpro.com\/wp-content\/uploads\/2026\/02\/400_PeerReview_Logo-1-48x48.jpg 48w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><div class=\"eedee-background-div__overlay\" style=\"opacity:1;\"><\/div><\/div><div class=\"slide-content\">\n\n<div class=\"wp-block-uagb-image uagb-block-8e11d08f wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><img decoding=\"async\" src=\"https:\/\/www.zinpro.com\/wp-content\/uploads\/2026\/02\/400_PeerReview_Logo-1.jpg\" alt=\"\" class=\"uag-image-72440\" width=\"500\" height=\"349\" title=\"400_Revisi\u00f3n por pares_Logotipo\" loading=\"lazy\" role=\"img\" \/><\/figure><\/div>\n\n<\/div><\/div>\n\n<div class=\"swiper-slide wp-block-eedee-block-gutenslide is-position-center-center ed-bg-image\" style=\"--ed-vw:300;--ed-vh:300;\" data-hash=\"\"><div class=\"eedee-background-div bg-image\"><img loading=\"lazy\" width=\"578\" height=\"579\" class=\"wp-image-74028\" src=\"https:\/\/www.zinpro.com\/wp-content\/uploads\/2026\/06\/AboutZinpro-55Years.png\" alt=\"\" decoding=\"async\" style=\"object-fit: cover; object-position: 72% 56%;\"  data-title=\"AboutZinpro-55Years\" srcset=\"https:\/\/www.zinpro.com\/wp-content\/uploads\/2026\/06\/AboutZinpro-55Years.png 578w, https:\/\/www.zinpro.com\/wp-content\/uploads\/2026\/06\/AboutZinpro-55Years-300x300.png 300w, https:\/\/www.zinpro.com\/wp-content\/uploads\/2026\/06\/AboutZinpro-55Years-150x150.png 150w, https:\/\/www.zinpro.com\/wp-content\/uploads\/2026\/06\/AboutZinpro-55Years-50x50.png 50w, https:\/\/www.zinpro.com\/wp-content\/uploads\/2026\/06\/AboutZinpro-55Years-12x12.png 12w, https:\/\/www.zinpro.com\/wp-content\/uploads\/2026\/06\/AboutZinpro-55Years-24x24.png 24w, https:\/\/www.zinpro.com\/wp-content\/uploads\/2026\/06\/AboutZinpro-55Years-36x36.png 36w, https:\/\/www.zinpro.com\/wp-content\/uploads\/2026\/06\/AboutZinpro-55Years-48x48.png 48w\" sizes=\"auto, (max-width: 578px) 100vw, 578px\" \/><div class=\"eedee-background-div__overlay\" style=\"opacity:1;\"><\/div><\/div><div class=\"slide-content\">\n\n<p class=\"has-text-align-center gutenslider-content-initial has-larger-font-size wp-block-paragraph\"><\/p>\n\n<\/div><\/div>\n\n<div class=\"swiper-slide wp-block-eedee-block-gutenslide is-position-center-center ed-bg-image\" style=\"--ed-vw:263;--ed-vh:300;\" data-hash=\"\"><div class=\"eedee-background-div bg-image\"><img loading=\"lazy\" width=\"560\" height=\"640\" class=\"wp-image-48080\" src=\"http:\/\/www.zinpro.com\/wp-content\/uploads\/2023\/04\/AboutZinpro-70Countries-560x640-1.png\" alt=\"\" decoding=\"async\" style=\"object-fit: cover; object-position: 50% 50%;\"  data-title=\"AboutZinpro-70Countries-560x640-1\" srcset=\"https:\/\/www.zinpro.com\/wp-content\/uploads\/2023\/04\/AboutZinpro-70Countries-560x640-1.png 560w, https:\/\/www.zinpro.com\/wp-content\/uploads\/2023\/04\/AboutZinpro-70Countries-560x640-1-263x300.png 263w, https:\/\/www.zinpro.com\/wp-content\/uploads\/2023\/04\/AboutZinpro-70Countries-560x640-1-11x12.png 11w\" sizes=\"auto, (max-width: 560px) 100vw, 560px\" \/><div class=\"eedee-background-div__overlay\" style=\"opacity:1;\"><\/div><\/div><div class=\"slide-content\">\n\n<p class=\"has-text-align-center gutenslider-content-initial has-larger-font-size wp-block-paragraph\"><\/p>\n\n<\/div><\/div>\n\n<div class=\"swiper-slide wp-block-eedee-block-gutenslide is-position-center-center ed-bg-image\" style=\"--ed-vw:263;--ed-vh:300;\" data-hash=\"\"><div class=\"eedee-background-div bg-image\"><img loading=\"lazy\" width=\"560\" height=\"640\" class=\"wp-image-48081\" src=\"http:\/\/www.zinpro.com\/wp-content\/uploads\/2023\/04\/AboutZinpro-500Patents-560x640-1.png\" alt=\"\" decoding=\"async\" style=\"object-fit: cover; object-position: 50% 50%;\"  data-title=\"AboutZinpro-500Patents-560x640-1\" srcset=\"https:\/\/www.zinpro.com\/wp-content\/uploads\/2023\/04\/AboutZinpro-500Patents-560x640-1.png 560w, https:\/\/www.zinpro.com\/wp-content\/uploads\/2023\/04\/AboutZinpro-500Patents-560x640-1-263x300.png 263w, https:\/\/www.zinpro.com\/wp-content\/uploads\/2023\/04\/AboutZinpro-500Patents-560x640-1-11x12.png 11w\" sizes=\"auto, (max-width: 560px) 100vw, 560px\" \/><div class=\"eedee-background-div__overlay\" style=\"opacity:1;\"><\/div><\/div><div class=\"slide-content\">\n\n<p class=\"has-text-align-center gutenslider-content-initial has-larger-font-size wp-block-paragraph\"><\/p>\n\n<\/div><\/div>\n<\/div><button class=\"eedee-gutenslider-nav eedee-gutenslider-prev\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 24 24\" width=\"24\" height=\"24\"><circle class=\"bg\" cx=\"13\" cy=\"12\" r=\"11\" \/><path fill=\"none\" d=\"M0 0h24v24H0z\"\/><path class=\"arrow\" d=\"M10.828 12l4.95 4.95-1.414 1.414L8 12l6.364-6.364 1.414 1.414z\"\/><\/svg><\/button><button class=\"eedee-gutenslider-nav eedee-gutenslider-next\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 24 24\" width=\"24\" height=\"24\"><circle class=\"bg\" cx=\"11\" cy=\"12\" r=\"11\" \/><path fill=\"none\" d=\"M0 0h24v24H0z\"\/><path class=\"arrow\" d=\"M13.172 12l-4.95-4.95 1.414-1.414L16 12l-6.364 6.364-1.414-1.414z\"\/><\/svg><\/button><div class=\"eedee-gutenslider-pagination\"><\/div><\/div><div class=\"gutenslider-divider-bottom\" style=\"color:#fff;\"><\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center wow fadeInUp anim-delay-300ms is-layout-flow wp-block-column-is-layout-flow\">\n<h3 class=\"wp-block-heading\" id=\"h-better-nutrition-for-a-better-world\">Mejor nutrici\u00f3n para un mundo mejor<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Con el respaldo de una amplia investigaci\u00f3n y de pr\u00e1cticas y soluciones l\u00edderes en el sector, ayudamos a los clientes a alcanzar de forma sostenible su mejor nivel, proporcion\u00e1ndoles una mayor nutrici\u00f3n y bienestar en todo el mundo.<\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-group is-layout-constrained wp-block-group-is-layout-constrained\">\n<div class=\"wp-block-cover wow fadeInUp anim-delay-300ms\"><img loading=\"lazy\" decoding=\"async\" width=\"1440\" height=\"675\" class=\"wp-block-cover__image-background wp-image-48087\" alt=\"\" src=\"https:\/\/www.zinpro.com\/wp-content\/uploads\/2023\/04\/OurBrand-1440x675-1.jpg\" data-object-fit=\"cover\" srcset=\"https:\/\/www.zinpro.com\/wp-content\/uploads\/2023\/04\/OurBrand-1440x675-1.jpg 1440w, https:\/\/www.zinpro.com\/wp-content\/uploads\/2023\/04\/OurBrand-1440x675-1-300x141.jpg 300w, https:\/\/www.zinpro.com\/wp-content\/uploads\/2023\/04\/OurBrand-1440x675-1-1024x480.jpg 1024w, https:\/\/www.zinpro.com\/wp-content\/uploads\/2023\/04\/OurBrand-1440x675-1-18x8.jpg 18w, https:\/\/www.zinpro.com\/wp-content\/uploads\/2023\/04\/OurBrand-1440x675-1-768x360.jpg 768w\" sizes=\"auto, (max-width: 1440px) 100vw, 1440px\" \/><span aria-hidden=\"true\" class=\"wp-block-cover__background has-background-dim-60 has-background-dim\"><\/span><div class=\"wp-block-cover__inner-container is-layout-flow wp-block-cover-is-layout-flow\">\n<h3 class=\"wp-block-heading has-text-align-center\" id=\"h-our-mission-vision-and-values\">Nuestra misi\u00f3n, visi\u00f3n y valores<\/h3>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-style-padded is-layout-flow wp-block-column-is-layout-flow\">\n<h4 class=\"wp-block-heading\" id=\"h-our-mission\"><strong>Nuestra misi\u00f3n<\/strong><\/h4>\n\n\n\n<p class=\"has-white-color has-text-color wp-block-paragraph\">Juntos trabajamos para mejorar la salud y el bienestar de animales y personas.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-style-padded is-layout-flow wp-block-column-is-layout-flow\">\n<h4 class=\"wp-block-heading\" id=\"h-our-vision\"><strong>Nuestra visi\u00f3n<\/strong><\/h4>\n\n\n\n<p class=\"has-white-color has-text-color wp-block-paragraph\">Cuando los animales y las personas gozan de mejor salud y bienestar, vemos un mundo m\u00e1s sano, productivo y sostenible para todos.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-style-padded is-layout-flow wp-block-column-is-layout-flow\">\n<h4 class=\"wp-block-heading\" id=\"h-our-values\"><strong>Nuestros valores<\/strong><\/h4>\n\n\n\n<p class=\"has-white-color has-text-color wp-block-paragraph\">Construir confianza | Ganar juntos | Servir con generosidad | Mejorar siempre | So\u00f1ar a lo grande<\/p>\n<\/div>\n<\/div>\n<\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-group is-layout-constrained wp-block-group-is-layout-constrained\">\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column wow fadeInUp is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"480\" src=\"https:\/\/www.zinpro.com\/wp-content\/uploads\/2023\/04\/SocialResponsibility.jpg\" alt=\"\" class=\"wp-image-48067\" srcset=\"https:\/\/www.zinpro.com\/wp-content\/uploads\/2023\/04\/SocialResponsibility.jpg 640w, https:\/\/www.zinpro.com\/wp-content\/uploads\/2023\/04\/SocialResponsibility-300x225.jpg 300w, https:\/\/www.zinpro.com\/wp-content\/uploads\/2023\/04\/SocialResponsibility-16x12.jpg 16w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/figure>\n\n\n\n<h5 class=\"wp-block-heading\" id=\"h-corporate-and-social-responsibility\">Responsabilidad social de las empresas<br><\/h5>\n\n\n\n<p class=\"wp-block-paragraph\">Nuestras asociaciones con organizaciones centradas en las personas y la sostenibilidad contribuyen a crear un mundo m\u00e1s sano y sostenible. Por eso nos comprometemos a apoyar a las comunidades en las que vivimos y trabajamos. Contribuimos activamente a la sociedad a trav\u00e9s de la financiaci\u00f3n de la investigaci\u00f3n, las contribuciones ben\u00e9ficas, el servicio a la comunidad y las actividades educativas.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column wow fadeInUp anim-delay-300ms is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/andersonfound.org\/\" target=\"_blank\" rel=\"noreferrer noopener\"><img loading=\"lazy\" decoding=\"async\" width=\"360\" height=\"330\" src=\"https:\/\/www.zinpro.com\/wp-content\/uploads\/2023\/04\/AZ-Anderson-Foundation-1.png\" alt=\"\" class=\"wp-image-48175\" srcset=\"https:\/\/www.zinpro.com\/wp-content\/uploads\/2023\/04\/AZ-Anderson-Foundation-1.png 360w, https:\/\/www.zinpro.com\/wp-content\/uploads\/2023\/04\/AZ-Anderson-Foundation-1-300x275.png 300w, https:\/\/www.zinpro.com\/wp-content\/uploads\/2023\/04\/AZ-Anderson-Foundation-1-13x12.png 13w\" sizes=\"auto, (max-width: 360px) 100vw, 360px\" \/><\/a><\/figure>\n\n\n\n<h5 class=\"wp-block-heading\" id=\"h-anderson-foundation\">Fundaci\u00f3n Anderson<\/h5>\n\n\n\n<p class=\"wp-block-paragraph\">La Fundaci\u00f3n Anderson fue creada por la familia Anderson en 1999 para honrar el esp\u00edritu humano y generoso de nuestros fundadores, Dean y Mary Anderson. Gracias a la cuidadosa administraci\u00f3n de los empleados de Zinpro, cada a\u00f1o una parte de nuestros beneficios se destina a las buenas obras de la Fundaci\u00f3n Anderson.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column wow fadeInUp anim-delay-600ms is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"480\" src=\"https:\/\/www.zinpro.com\/wp-content\/uploads\/2023\/04\/EmployeeSafety.jpg\" alt=\"\" class=\"wp-image-48069\" srcset=\"https:\/\/www.zinpro.com\/wp-content\/uploads\/2023\/04\/EmployeeSafety.jpg 640w, https:\/\/www.zinpro.com\/wp-content\/uploads\/2023\/04\/EmployeeSafety-300x225.jpg 300w, https:\/\/www.zinpro.com\/wp-content\/uploads\/2023\/04\/EmployeeSafety-16x12.jpg 16w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/figure>\n\n\n\n<h5 class=\"wp-block-heading\" id=\"h-employee-safety\">Seguridad de los trabajadores<\/h5>\n\n\n\n<p class=\"wp-block-paragraph\">La seguridad de nuestros empleados es siempre lo primero. Controlamos constantemente su seguridad, ya trabajen en nuestro laboratorio, en la planta de producci\u00f3n, en nuestros almacenes u oficinas, o mientras viajan o transportan materiales.<\/p>\n<\/div>\n<\/div>\n\n\n\n\n<div id=\"resp-spacer-block_760b1e38835868b90d8cb78b8b586898\" class=\"zinpro-spacer-block\"><\/div>\n\n<style>\n#resp-spacer-block_760b1e38835868b90d8cb78b8b586898 {\n\tmargin-top: 80px;\n}\n\n@media screen and (max-width: 1366px) {\n\t#resp-spacer-block_760b1e38835868b90d8cb78b8b586898 {\n\t\tmargin-top: 60px;\n\t}\n}\n\n@media screen and (max-width: 960px) {\n\t#resp-spacer-block_760b1e38835868b90d8cb78b8b586898 {\n\t\tmargin-top: 40px;\n\t}\n}\n<\/style>\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column wow fadeInUp is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"480\" src=\"https:\/\/www.zinpro.com\/wp-content\/uploads\/2023\/04\/EnvironmentalResponsibility.jpg\" alt=\"\" class=\"wp-image-48073\" srcset=\"https:\/\/www.zinpro.com\/wp-content\/uploads\/2023\/04\/EnvironmentalResponsibility.jpg 640w, https:\/\/www.zinpro.com\/wp-content\/uploads\/2023\/04\/EnvironmentalResponsibility-300x225.jpg 300w, https:\/\/www.zinpro.com\/wp-content\/uploads\/2023\/04\/EnvironmentalResponsibility-16x12.jpg 16w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/figure>\n\n\n\n<h5 class=\"wp-block-heading\" id=\"h-environmental-responsibility\">Responsabilidad medioambiental<\/h5>\n\n\n\n<p class=\"wp-block-paragraph\">Desarrollamos continuamente nuevos m\u00e9todos de producci\u00f3n y perfeccionamos nuestras pr\u00e1cticas de transporte y emisiones para que nuestro negocio sea lo m\u00e1s sostenible posible.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column wow fadeInUp anim-delay-300ms is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"480\" src=\"https:\/\/www.zinpro.com\/wp-content\/uploads\/2023\/04\/AdvancingScience.jpg\" alt=\"\" class=\"wp-image-48074\" srcset=\"https:\/\/www.zinpro.com\/wp-content\/uploads\/2023\/04\/AdvancingScience.jpg 640w, https:\/\/www.zinpro.com\/wp-content\/uploads\/2023\/04\/AdvancingScience-300x225.jpg 300w, https:\/\/www.zinpro.com\/wp-content\/uploads\/2023\/04\/AdvancingScience-16x12.jpg 16w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/figure>\n\n\n\n<h5 class=\"wp-block-heading\" id=\"h-advancing-science-and-technology\">Avance de la ciencia y la tecnolog\u00eda<\/h5>\n\n\n\n<p class=\"wp-block-paragraph\">Nuestras publicaciones revisadas por expertos son la prueba de que investigamos constantemente para encontrar las mejores soluciones para nuestros clientes.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column wow fadeInUp anim-delay-600ms is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"480\" src=\"https:\/\/www.zinpro.com\/wp-content\/uploads\/2023\/04\/EconomicSupport.jpg\" alt=\"\" class=\"wp-image-48075\" srcset=\"https:\/\/www.zinpro.com\/wp-content\/uploads\/2023\/04\/EconomicSupport.jpg 640w, https:\/\/www.zinpro.com\/wp-content\/uploads\/2023\/04\/EconomicSupport-300x225.jpg 300w, https:\/\/www.zinpro.com\/wp-content\/uploads\/2023\/04\/EconomicSupport-16x12.jpg 16w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/figure>\n\n\n\n<h5 class=\"wp-block-heading\" id=\"h-economic-support\">Apoyo econ\u00f3mico<\/h5>\n\n\n\n<p class=\"wp-block-paragraph\">La investigaci\u00f3n ha demostrado que hay un impacto significativo en el bienestar de los animales cuando Zinpro\u00ae Performance Minerals\u00ae se incluyen como parte de una dieta equilibrada. El aumento del bienestar y el rendimiento proporciona a nuestros clientes ventajas sustanciales.<\/p>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-group alignfull has-background is-layout-constrained wp-block-group-is-layout-constrained\" style=\"background-color:#f7f7f7\">\n<div class=\"wp-block-cover is-light wow fadeInUp\"><img loading=\"lazy\" decoding=\"async\" width=\"1436\" height=\"576\" class=\"wp-block-cover__image-background wp-image-48101\" alt=\"\" src=\"http:\/\/www.zinpro.com\/wp-content\/uploads\/2023\/04\/AboutUs_Experts_-e1673479153231.jpg\" data-object-fit=\"cover\" srcset=\"https:\/\/www.zinpro.com\/wp-content\/uploads\/2023\/04\/AboutUs_Experts_-e1673479153231.jpg 1436w, https:\/\/www.zinpro.com\/wp-content\/uploads\/2023\/04\/AboutUs_Experts_-e1673479153231-300x120.jpg 300w, https:\/\/www.zinpro.com\/wp-content\/uploads\/2023\/04\/AboutUs_Experts_-e1673479153231-1024x411.jpg 1024w, https:\/\/www.zinpro.com\/wp-content\/uploads\/2023\/04\/AboutUs_Experts_-e1673479153231-18x7.jpg 18w\" sizes=\"auto, (max-width: 1436px) 100vw, 1436px\" \/><span aria-hidden=\"true\" class=\"wp-block-cover__background has-background-dim-30 has-background-dim wp-block-cover__gradient-background has-background-gradient\" style=\"background:linear-gradient(91deg,rgb(0,0,0) 11%,rgba(255,255,255,0) 56%)\"><\/span><div class=\"wp-block-cover__inner-container is-layout-flow wp-block-cover-is-layout-flow\">\n<h1 class=\"wp-block-heading has-white-color has-text-color\" id=\"h-get-connected-with-an-expert\">Con\u00e9ctate <br>con un experto<\/h1>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-group is-layout-constrained wp-container-core-group-is-layout-78cc654d wp-block-group-is-layout-constrained\">\n\n<div id=\"resp-spacer-block_7c38b78622eb386a59687cc56585243b\" class=\"zinpro-spacer-block\"><\/div>\n\n<style>\n#resp-spacer-block_7c38b78622eb386a59687cc56585243b {\n\tmargin-top: 60px;\n}\n\n@media screen and (max-width: 1366px) {\n\t#resp-spacer-block_7c38b78622eb386a59687cc56585243b {\n\t\tmargin-top: 40px;\n\t}\n}\n\n@media screen and (max-width: 960px) {\n\t#resp-spacer-block_7c38b78622eb386a59687cc56585243b {\n\t\tmargin-top: 20px;\n\t}\n}\n<\/style>\n\n\n<h6 class=\"wp-block-heading wow fadeInUp\" id=\"h-learn-more-about-how-the-culture-commitment-and-science-at-zinpro-can-help-your-business\">Obtenga m\u00e1s informaci\u00f3n sobre c\u00f3mo la cultura, el compromiso y la ciencia de Zinpro pueden ayudar a su empresa.<\/h6>\n\n\n\n<div class=\"wp-block-buttons wow fadeInUp is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\" id=\"wow-fadeInUp\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/www.zinpro.com\/es_mx\/lets-connect\/\">Cont\u00e1ctanos<\/a><\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>","protected":false},"excerpt":{"rendered":"<p>About Zinpro\u00ae Corporation<\/p>\n<p>#resp-spacer-block_760b1e38835868b90d8cb78b8b586898 {<br \/>\n\tmargin-top: 80px;<br \/>\n}<\/p>\n<p>@media screen and (max-width: 1366px) {<br \/>\n\t#resp-spacer-block_760b1e38835868b90d8cb78b8b586898 {<br \/>\n\t\tmargin-top: 60px;<br \/>\n\t}<br \/>\n}<\/p>\n<p>@media screen and (max-width: 960px) {<br \/>\n\t#resp-spacer-block_760b1e38835868b90d8cb78b8b586898 {<br \/>\n\t\tmargin-top: 40px;<br \/>\n\t}<br \/>\n}<\/p>\n<p class=\"wp-block-paragraph\">For more than 50 years, Zinpro [&#8230;]<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_tec_requires_first_save":true,"_eb_attr":"","_uag_custom_page_level_css":"","_EventAllDay":false,"_EventTimezone":"","_EventStartDate":"","_EventEndDate":"","_EventStartDateUTC":"","_EventEndDateUTC":"","_EventShowMap":false,"_EventShowMapLink":false,"_EventURL":"","_EventCost":"","_EventCostDescription":"","_EventCurrencySymbol":"","_EventCurrencyCode":"","_EventCurrencyPosition":"","_EventDateTimeSeparator":"","_EventTimeRangeSeparator":"","_EventOrganizerID":[],"_EventVenueID":[],"_OrganizerEmail":"","_OrganizerPhone":"","_OrganizerWebsite":"","_VenueAddress":"","_VenueCity":"","_VenueCountry":"","_VenueProvince":"","_VenueState":"","_VenueZip":"","_VenuePhone":"","_VenueURL":"","_VenueStateProvince":"","_VenueLat":"","_VenueLng":"","_VenueShowMap":false,"_VenueShowMapLink":false,"_tribe_blocks_recurrence_rules":"","_tribe_blocks_recurrence_description":"","_tribe_blocks_recurrence_exclusions":"","_ecp_custom_2":"","footnotes":""},"class_list":["post-306","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>About Zinpro Corporation &#8211; Zinpro\u00ae<\/title>\n<meta name=\"description\" content=\"Learn more about how our culture, commitment and science can help your business by getting in touch with one of our representatives today.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.zinpro.com\/es_mx\/about\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"About Zinpro Corporation &#8211; Zinpro\u00ae\" \/>\n<meta property=\"og:description\" content=\"Learn more about how our culture, commitment and science can help your business by getting in touch with one of our representatives today.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.zinpro.com\/es_mx\/about\/\" \/>\n<meta property=\"og:site_name\" content=\"Zinpro\u00ae\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ZinproCorp\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-05T14:54:14+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.zinpro.com\/wp-content\/uploads\/2023\/04\/AboutHero.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@wdolezal\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.zinpro.com\\\/about\\\/\",\"url\":\"https:\\\/\\\/www.zinpro.com\\\/about\\\/\",\"name\":\"About Zinpro Corporation &#8211; Zinpro\u00ae\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.zinpro.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.zinpro.com\\\/about\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.zinpro.com\\\/about\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.zinpro.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/AboutHero.jpg\",\"datePublished\":\"2022-08-15T14:42:32+00:00\",\"dateModified\":\"2026-06-05T14:54:14+00:00\",\"description\":\"Learn more about how our culture, commitment and science can help your business by getting in touch with one of our representatives today.\",\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.zinpro.com\\\/about\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.zinpro.com\\\/about\\\/#primaryimage\",\"url\":\"http:\\\/\\\/www.zinpro.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/AboutHero.jpg\",\"contentUrl\":\"http:\\\/\\\/www.zinpro.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/AboutHero.jpg\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.zinpro.com\\\/#website\",\"url\":\"https:\\\/\\\/www.zinpro.com\\\/\",\"name\":\"Zinpro\u00ae\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.zinpro.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Acerca de Zinpro Corporation - Zinpro","description":"Obtenga m\u00e1s informaci\u00f3n sobre c\u00f3mo nuestra cultura, compromiso y ciencia pueden ayudar a su empresa poni\u00e9ndose en contacto con uno de nuestros representantes hoy mismo.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.zinpro.com\/es_mx\/about\/","og_locale":"es_MX","og_type":"article","og_title":"About Zinpro Corporation &#8211; Zinpro\u00ae","og_description":"Learn more about how our culture, commitment and science can help your business by getting in touch with one of our representatives today.","og_url":"https:\/\/www.zinpro.com\/es_mx\/about\/","og_site_name":"Zinpro\u00ae","article_publisher":"https:\/\/www.facebook.com\/ZinproCorp\/","article_modified_time":"2026-06-05T14:54:14+00:00","og_image":[{"url":"http:\/\/www.zinpro.com\/wp-content\/uploads\/2023\/04\/AboutHero.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_site":"@wdolezal","twitter_misc":{"Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.zinpro.com\/about\/","url":"https:\/\/www.zinpro.com\/about\/","name":"Acerca de Zinpro Corporation - Zinpro","isPartOf":{"@id":"https:\/\/www.zinpro.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.zinpro.com\/about\/#primaryimage"},"image":{"@id":"https:\/\/www.zinpro.com\/about\/#primaryimage"},"thumbnailUrl":"http:\/\/www.zinpro.com\/wp-content\/uploads\/2023\/04\/AboutHero.jpg","datePublished":"2022-08-15T14:42:32+00:00","dateModified":"2026-06-05T14:54:14+00:00","description":"Obtenga m\u00e1s informaci\u00f3n sobre c\u00f3mo nuestra cultura, compromiso y ciencia pueden ayudar a su empresa poni\u00e9ndose en contacto con uno de nuestros representantes hoy mismo.","inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.zinpro.com\/about\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.zinpro.com\/about\/#primaryimage","url":"http:\/\/www.zinpro.com\/wp-content\/uploads\/2023\/04\/AboutHero.jpg","contentUrl":"http:\/\/www.zinpro.com\/wp-content\/uploads\/2023\/04\/AboutHero.jpg"},{"@type":"WebSite","@id":"https:\/\/www.zinpro.com\/#website","url":"https:\/\/www.zinpro.com\/","name":"Zinpro","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.zinpro.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"spectra_custom_meta":{"_edit_lock":["1780671316:8"],"_oembed_708cc253cdbaa4bc8081a8ef9ffff158":["<iframe title=\"Zinpro Brand Video\" width=\"640\" height=\"360\" src=\"https:\/\/www.youtube.com\/embed\/XWkNHeZiOGE?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe>"],"_oembed_time_708cc253cdbaa4bc8081a8ef9ffff158":["1689726911"],"_edit_last":["8"],"_yoast_wpseo_content_score":["30"],"_yoast_wpseo_estimated-reading-time-minutes":["4"],"_yoast_wpseo_wordproof_timestamp":[""],"ss_social_share_disable":[""],"_yoast_wpseo_title":["About Zinpro Corporation %%sep%% %%sitename%%"],"_yoast_wpseo_metadesc":["Learn more about how our culture, commitment and science can help your business by getting in touch with one of our representatives today."],"_yoast_wpseo_focuskeywords":["[]"],"_yoast_wpseo_keywordsynonyms":["[\"\"]"],"_eb_reusable_block_ids":["a:0:{}"],"_uagb_previous_block_counts":["a:90:{s:21:\"uagb\/advanced-heading\";i:0;s:15:\"uagb\/blockquote\";i:0;s:12:\"uagb\/buttons\";i:0;s:18:\"uagb\/buttons-child\";i:0;s:19:\"uagb\/call-to-action\";i:0;s:15:\"uagb\/cf7-styler\";i:0;s:11:\"uagb\/column\";i:0;s:12:\"uagb\/columns\";i:0;s:14:\"uagb\/container\";i:0;s:21:\"uagb\/content-timeline\";i:0;s:27:\"uagb\/content-timeline-child\";i:0;s:14:\"uagb\/countdown\";i:0;s:12:\"uagb\/counter\";i:0;s:8:\"uagb\/faq\";i:0;s:14:\"uagb\/faq-child\";i:0;s:10:\"uagb\/forms\";i:0;s:17:\"uagb\/forms-accept\";i:0;s:19:\"uagb\/forms-checkbox\";i:0;s:15:\"uagb\/forms-date\";i:0;s:16:\"uagb\/forms-email\";i:0;s:17:\"uagb\/forms-hidden\";i:0;s:15:\"uagb\/forms-name\";i:0;s:16:\"uagb\/forms-phone\";i:0;s:16:\"uagb\/forms-radio\";i:0;s:17:\"uagb\/forms-select\";i:0;s:19:\"uagb\/forms-textarea\";i:0;s:17:\"uagb\/forms-toggle\";i:0;s:14:\"uagb\/forms-url\";i:0;s:14:\"uagb\/gf-styler\";i:0;s:15:\"uagb\/google-map\";i:0;s:11:\"uagb\/how-to\";i:0;s:16:\"uagb\/how-to-step\";i:0;s:9:\"uagb\/icon\";i:0;s:14:\"uagb\/icon-list\";i:0;s:20:\"uagb\/icon-list-child\";i:0;s:10:\"uagb\/image\";i:1;s:18:\"uagb\/image-gallery\";i:0;s:13:\"uagb\/info-box\";i:0;s:18:\"uagb\/inline-notice\";i:0;s:11:\"uagb\/lottie\";i:0;s:21:\"uagb\/marketing-button\";i:0;s:10:\"uagb\/modal\";i:0;s:18:\"uagb\/popup-builder\";i:0;s:16:\"uagb\/post-button\";i:0;s:18:\"uagb\/post-carousel\";i:0;s:17:\"uagb\/post-excerpt\";i:0;s:14:\"uagb\/post-grid\";i:0;s:15:\"uagb\/post-image\";i:0;s:17:\"uagb\/post-masonry\";i:0;s:14:\"uagb\/post-meta\";i:0;s:18:\"uagb\/post-taxonomy\";i:0;s:18:\"uagb\/post-timeline\";i:0;s:15:\"uagb\/post-title\";i:0;s:20:\"uagb\/restaurant-menu\";i:0;s:26:\"uagb\/restaurant-menu-child\";i:0;s:11:\"uagb\/review\";i:0;s:12:\"uagb\/section\";i:0;s:14:\"uagb\/separator\";i:0;s:11:\"uagb\/slider\";i:0;s:17:\"uagb\/slider-child\";i:0;s:17:\"uagb\/social-share\";i:0;s:23:\"uagb\/social-share-child\";i:0;s:16:\"uagb\/star-rating\";i:0;s:23:\"uagb\/sure-cart-checkout\";i:0;s:22:\"uagb\/sure-cart-product\";i:0;s:15:\"uagb\/sure-forms\";i:0;s:22:\"uagb\/table-of-contents\";i:0;s:9:\"uagb\/tabs\";i:0;s:15:\"uagb\/tabs-child\";i:0;s:18:\"uagb\/taxonomy-list\";i:0;s:9:\"uagb\/team\";i:0;s:16:\"uagb\/testimonial\";i:0;s:14:\"uagb\/wp-search\";i:0;s:19:\"uagb\/instagram-feed\";i:0;s:10:\"uagb\/login\";i:0;s:17:\"uagb\/loop-builder\";i:0;s:18:\"uagb\/loop-category\";i:0;s:20:\"uagb\/loop-pagination\";i:0;s:15:\"uagb\/loop-reset\";i:0;s:16:\"uagb\/loop-search\";i:0;s:14:\"uagb\/loop-sort\";i:0;s:17:\"uagb\/loop-wrapper\";i:0;s:13:\"uagb\/register\";i:0;s:19:\"uagb\/register-email\";i:0;s:24:\"uagb\/register-first-name\";i:0;s:23:\"uagb\/register-last-name\";i:0;s:22:\"uagb\/register-password\";i:0;s:30:\"uagb\/register-reenter-password\";i:0;s:19:\"uagb\/register-terms\";i:0;s:22:\"uagb\/register-username\";i:0;}"],"_uagb_last_spectra_edit":["1777183691"],"_uag_css_file_name":["uag-css-306.css"],"_uag_page_assets":["a:9:{s:3:\"css\";s:7133:\".wp-block-uagb-image{display:flex}.wp-block-uagb-image__figure{position:relative;display:flex;flex-direction:column;max-width:100%;height:auto;margin:0}.wp-block-uagb-image__figure img{height:auto;display:flex;max-width:100%;transition:box-shadow .2s ease}.wp-block-uagb-image__figure>a{display:inline-block}.wp-block-uagb-image__figure figcaption{text-align:center;margin-top:.5em;margin-bottom:1em}.wp-block-uagb-image .components-placeholder.block-editor-media-placeholder .components-placeholder__instructions{align-self:center}.wp-block-uagb-image--align-left{text-align:left}.wp-block-uagb-image--align-right{text-align:right}.wp-block-uagb-image--align-center{text-align:center}.wp-block-uagb-image--align-full .wp-block-uagb-image__figure{margin-left:calc(50% - 50vw);margin-right:calc(50% - 50vw);max-width:100vw;width:100vw;height:auto}.wp-block-uagb-image--align-full .wp-block-uagb-image__figure img{height:auto;width:100% !important}.wp-block-uagb-image--align-wide .wp-block-uagb-image__figure img{height:auto;width:100%}.wp-block-uagb-image--layout-overlay__color-wrapper{position:absolute;left:0;top:0;right:0;bottom:0;opacity:.2;background:rgba(0,0,0,.5);transition:opacity .35s ease-in-out}.wp-block-uagb-image--layout-overlay-link{position:absolute;left:0;right:0;bottom:0;top:0}.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity:1}.wp-block-uagb-image--layout-overlay__inner{position:absolute;left:15px;right:15px;bottom:15px;top:15px;display:flex;align-items:center;justify-content:center;flex-direction:column;border-color:#fff;transition:.35s ease-in-out}.wp-block-uagb-image--layout-overlay__inner.top-left,.wp-block-uagb-image--layout-overlay__inner.top-center,.wp-block-uagb-image--layout-overlay__inner.top-right{justify-content:flex-start}.wp-block-uagb-image--layout-overlay__inner.bottom-left,.wp-block-uagb-image--layout-overlay__inner.bottom-center,.wp-block-uagb-image--layout-overlay__inner.bottom-right{justify-content:flex-end}.wp-block-uagb-image--layout-overlay__inner.top-left,.wp-block-uagb-image--layout-overlay__inner.center-left,.wp-block-uagb-image--layout-overlay__inner.bottom-left{align-items:flex-start}.wp-block-uagb-image--layout-overlay__inner.top-right,.wp-block-uagb-image--layout-overlay__inner.center-right,.wp-block-uagb-image--layout-overlay__inner.bottom-right{align-items:flex-end}.wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{color:#fff;transition:transform .35s,opacity .35s ease-in-out;transform:translate3d(0, 24px, 0);margin:0;line-height:1em}.wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width:30%;border-top-width:2px;border-top-color:#fff;border-top-style:solid;margin-bottom:10px;opacity:0;transition:transform .4s,opacity .4s ease-in-out;transform:translate3d(0, 30px, 0)}.wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity:0;overflow:visible;color:#fff;transition:transform .45s,opacity .45s ease-in-out;transform:translate3d(0, 35px, 0)}.wp-block-uagb-image--layout-overlay__inner:hover .uagb-image-heading,.wp-block-uagb-image--layout-overlay__inner:hover .uagb-image-separator,.wp-block-uagb-image--layout-overlay__inner:hover .uagb-image-caption{opacity:1;transform:translate3d(0, 0, 0)}.wp-block-uagb-image--effect-zoomin .wp-block-uagb-image__figure img,.wp-block-uagb-image--effect-zoomin .wp-block-uagb-image__figure .wp-block-uagb-image--layout-overlay__color-wrapper{transform:scale(1);transition:transform .35s ease-in-out}.wp-block-uagb-image--effect-zoomin .wp-block-uagb-image__figure:hover img,.wp-block-uagb-image--effect-zoomin .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{transform:scale(1.05)}.wp-block-uagb-image--effect-slide .wp-block-uagb-image__figure img,.wp-block-uagb-image--effect-slide .wp-block-uagb-image__figure .wp-block-uagb-image--layout-overlay__color-wrapper{width:calc(100% + 40px) !important;max-width:none !important;transform:translate3d(-40px, 0, 0);transition:transform .35s ease-in-out}.wp-block-uagb-image--effect-slide .wp-block-uagb-image__figure:hover img,.wp-block-uagb-image--effect-slide .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{transform:translate3d(0, 0, 0)}.wp-block-uagb-image--effect-grayscale img{filter:grayscale(0%);transition:.35s ease-in-out}.wp-block-uagb-image--effect-grayscale:hover img{filter:grayscale(100%)}.wp-block-uagb-image--effect-blur img{filter:blur(0);transition:.35s ease-in-out}.wp-block-uagb-image--effect-blur:hover img{filter:blur(3px)}.uagb-block-8e11d08f.wp-block-uagb-image--layout-default figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-8e11d08f.wp-block-uagb-image .wp-block-uagb-image__figure figcaption{font-style: normal;align-self: center;}.uagb-block-8e11d08f.wp-block-uagb-image--layout-overlay figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-8e11d08f.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 0.2;}.uagb-block-8e11d08f.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner{left: 15px;right: 15px;top: 15px;bottom: 15px;}.uagb-block-8e11d08f.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{font-style: normal;color: #fff;opacity: 1;}.uagb-block-8e11d08f.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading a{color: #fff;}.uagb-block-8e11d08f.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 0;}.uagb-block-8e11d08f.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 1;}.uagb-block-8e11d08f.wp-block-uagb-image .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width: 30%;border-top-width: 2px;border-top-color: #fff;opacity: 0;}.uagb-block-8e11d08f.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.uagb-block-8e11d08f.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 1;}.uagb-block-8e11d08f.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{opacity: 1;}.uagb-block-8e11d08f.wp-block-uagb-image--layout-default figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-8e11d08f.wp-block-uagb-image--layout-overlay figure:hover img{box-shadow: 0px 0px 0 #00000070;}@media only screen and (max-width: 976px) {.uagb-block-8e11d08f.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}}@media only screen and (max-width: 767px) {.uagb-block-8e11d08f.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}}.uag-blocks-common-selector{z-index:var(--z-index-desktop) !important}@media(max-width: 976px){.uag-blocks-common-selector{z-index:var(--z-index-tablet) !important}}@media(max-width: 767px){.uag-blocks-common-selector{z-index:var(--z-index-mobile) !important}}\";s:2:\"js\";s:0:\"\";s:18:\"current_block_list\";a:22:{i:0;s:10:\"core\/cover\";i:1;s:12:\"core\/heading\";i:2;s:24:\"zinpro\/responsive-spacer\";i:3;s:12:\"core\/columns\";i:4;s:11:\"core\/column\";i:5;s:14:\"core\/paragraph\";i:7;s:12:\"epyt\/youtube\";i:10;s:23:\"eedee\/block-gutenslider\";i:11;s:22:\"eedee\/block-gutenslide\";i:12;s:10:\"uagb\/image\";i:13;s:10:\"core\/group\";i:17;s:10:\"core\/image\";i:18;s:12:\"core\/buttons\";i:19;s:11:\"core\/button\";i:20;s:11:\"core\/search\";i:21;s:17:\"core\/latest-posts\";i:22;s:20:\"core\/latest-comments\";i:23;s:13:\"core\/archives\";i:24;s:15:\"core\/categories\";i:25;s:17:\"core\/social-links\";i:26;s:16:\"core\/social-link\";i:27;s:11:\"core\/spacer\";}s:8:\"uag_flag\";b:1;s:11:\"uag_version\";s:10:\"1784070789\";s:6:\"gfonts\";a:0:{}s:10:\"gfonts_url\";s:0:\"\";s:12:\"gfonts_files\";a:0:{}s:14:\"uag_faq_layout\";b:0;}"]},"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"gs-tiny":false,"xl":false,"xxl":false,"xxxl":false,"xxxxl":false,"xxxxxl":false,"1536x1536":false,"2048x2048":false,"trp-custom-language-flag":false,"gform-image-choice-sm":false,"gform-image-choice-md":false,"gform-image-choice-lg":false,"menu-24x24":false,"menu-36x36":false,"menu-48x48":false},"uagb_author_info":{"display_name":"mrwolleat","author_link":"https:\/\/www.zinpro.com\/es_mx\/resource-center\/author\/mrwolleat\/"},"uagb_comment_info":0,"uagb_excerpt":"About Zinpro\u00ae Corporation #resp-spacer-block_760b1e38835868b90d8cb78b8b586898 { margin-top: 80px; } @media screen and (max-width: 1366px) { #resp-spacer-block_760b1e38835868b90d8cb78b8b586898 { margin-top: 60px; } } @media screen and (max-width: 960px) { #resp-spacer-block_760b1e38835868b90d8cb78b8b586898 { margin-top: 40px; } } For more than 50 years, Zinpro [...]","_links":{"self":[{"href":"https:\/\/www.zinpro.com\/es_mx\/wp-json\/wp\/v2\/pages\/306","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.zinpro.com\/es_mx\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.zinpro.com\/es_mx\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.zinpro.com\/es_mx\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.zinpro.com\/es_mx\/wp-json\/wp\/v2\/comments?post=306"}],"version-history":[{"count":1,"href":"https:\/\/www.zinpro.com\/es_mx\/wp-json\/wp\/v2\/pages\/306\/revisions"}],"predecessor-version":[{"id":74029,"href":"https:\/\/www.zinpro.com\/es_mx\/wp-json\/wp\/v2\/pages\/306\/revisions\/74029"}],"wp:attachment":[{"href":"https:\/\/www.zinpro.com\/es_mx\/wp-json\/wp\/v2\/media?parent=306"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}