

{"id":63201,"date":"2024-09-24T05:00:00","date_gmt":"2024-09-24T10:00:00","guid":{"rendered":"https:\/\/www.zinpro.com\/?post_type=news&#038;p=63201"},"modified":"2024-09-23T16:39:58","modified_gmt":"2024-09-23T21:39:58","slug":"zinpro-isoferm-wins-silver-medal-at-eurotier-innovation-awards","status":"publish","type":"news","link":"https:\/\/www.zinpro.com\/es_mx\/news\/zinpro-isoferm-wins-silver-medal-at-eurotier-innovation-awards\/","title":{"rendered":"Zinpro IsoFerm gana la Medalla de Plata en los Premios EuroTier a la Innovaci\u00f3n"},"content":{"rendered":"<p><em>Un producto innovador que mejora la eficacia, la rentabilidad y la sostenibilidad de las explotaciones.<\/em><\/p>\n\n\n\n<p>EDEN PRAIRIE, Minnesota - 24 de septiembre de 2024 - Zinpro\u00ae Corporation, l\u00edder mundial en innovaci\u00f3n y fabricaci\u00f3n de oligoelementos de alto rendimiento y soluciones de nutrici\u00f3n animal, se enorgullece de anunciar que su producto l\u00e1cteo, <a href=\"https:\/\/www.zinpro.com\/es_mx\/isoferm\/\">Zinpro<sup> <\/sup>IsoFerm<\/a>\u00ae, ha sido galardonada con la Medalla de Plata en los prestigiosos Premios EuroTier a la Innovaci\u00f3n.<\/p>\n\n\n\n<p>En <a href=\"https:\/\/www.eurotier.com\/en\/awards\/innovation-award\">Premios EuroTier a la innovaci\u00f3n<\/a> reconocen los productos m\u00e1s innovadores del sector de la ganader\u00eda y la gesti\u00f3n de animales. La Medalla de Plata se concede a productos que demuestran mejoras significativas en funcionalidad, eficiencia y sostenibilidad. Zinpro IsoFerm fue reconocido por su enfoque innovador para mejorar la nutrici\u00f3n y el rendimiento de los animales.<\/p>\n\n\n\n<p>\"Nos sentimos honrados de recibir este reconocimiento de EuroTier\", ha declarado Justin Howes, Director de Marketing Global de Rumiantes de Zinpro. \"Zinpro IsoFerm representa nuestro compromiso con el avance del rendimiento animal mediante una tecnolog\u00eda pionera que est\u00e1 remodelando la nutrici\u00f3n l\u00e1ctea. Este premio es un testimonio del duro trabajo y la dedicaci\u00f3n de nuestro equipo.\"<\/p>\n\n\n\n<p>Zinpro IsoFerm es una mezcla patentada de \u00e1cidos grasos vol\u00e1tiles de cadena ramificada (BCVFAs o iso\u00e1cidos) que son utilizados de forma natural por los microbios del rumen para producir prote\u00edna microbiana y energ\u00eda. Se trata de un producto innovador que mejora la fermentaci\u00f3n al alimentar a las bacterias que digieren la fibra en el rumen, lo que permite que las vacas sean m\u00e1s eficientes y productivas. Los iso\u00e1cidos han sido reconocidos como nutrientes necesarios durante d\u00e9cadas, pero la suplementaci\u00f3n en dietas deficientes era imposible hasta ahora.<\/p>\n\n\n\n<p>Algunas ventajas concretas son:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Rendimiento superior de las vacas en transici\u00f3n:<\/strong> Gracias a la mejora de la funci\u00f3n hep\u00e1tica al principio de la lactaci\u00f3n, las vacas experimentan una menor p\u00e9rdida de peso corporal, una menor cetosis y una mayor producci\u00f3n de glucosa.<\/li>\n\n\n\n<li><strong>Aumento de la producci\u00f3n lechera<\/strong>: Al mejorar la fermentaci\u00f3n, Zinpro IsoFerm ayuda a las vacas a producir m\u00e1s leche con menos recursos, logrando de forma constante un pico de producci\u00f3n de leche 10-12% superior.<\/li>\n\n\n\n<li><strong>Mejora de la eficiencia alimentaria<\/strong>: Mejora la funci\u00f3n natural del rumen, impulsando la digesti\u00f3n de las fibras y la utilizaci\u00f3n de las prote\u00ednas, a menudo con una menor ingesta de materia seca, lo que se traduce en una mayor eficiencia alimentaria.<\/li>\n\n\n\n<li><strong>Mayor eficiencia de las explotaciones<\/strong>: Las mejoras en la eficacia de la alimentaci\u00f3n y la producci\u00f3n contribuyen a una mayor eficiencia de las explotaciones, lo que se traduce en mayores ingresos por encima de los costes de alimentaci\u00f3n y en una mejora de los resultados finales.<\/li>\n\n\n\n<li><strong>Sostenibilidad medioambiental<\/strong>: Los avances en eficiencia y productividad de Zinpro IsoFerm tambi\u00e9n impulsan la sostenibilidad operativa y medioambiental.<\/li>\n<\/ul>\n\n\n\n<p>Los clientes y productores l\u00e1cteos que aplican Zinpro IsoFerm est\u00e1n observando beneficios econ\u00f3micos y de productividad en sus operaciones.<\/p>\n\n\n\n<p>\"Es agradable entrar en la sala de orde\u00f1o por la ma\u00f1ana y ver a nuestras vacas llenas de leche. Me encanta porque significa que estoy criando a mis vacas con el potencial que tienen ahora. Y el uso de Zinpro IsoFerm ha liberado realmente ese potencial en ellas\", dice Pippa Tudor, de Hallon Farm.<\/p>\n\n\n\n<p>Pete Davis, propietario y nutricionista de Cows 24-7, dice: \"No tenemos enfermedades de transici\u00f3n y tenemos vacas sanas. Est\u00e1 aumentando nuestra tasa de pre\u00f1ez, que ha subido unos 3\u00bd puntos porcentuales\".<\/p>\n\n\n\n<p>El premio a la innovaci\u00f3n se entregar\u00e1 oficialmente en el evento EuroTier el 12 de noviembre de 2024. Tim Horne, director regional de Zinpro para Europa y Sud\u00e1frica, afirma: \"Nuestro equipo est\u00e1 encantado de recibir la medalla de plata a la innovaci\u00f3n y estamos impacientes por dar la bienvenida a los visitantes de EuroTier a nuestro stand, donde mostraremos Zinpro IsoFerm y muchas otras ofertas de productos Zinpro.\"<\/p>","protected":false},"excerpt":{"rendered":"<p><em>Innovative product improves on-farm efficiency, profitability and sustainability.<\/em><\/p>\n<p>EDEN PRAIRIE, Minn. \u2013 September 24, 2024 \u2013 Zinpro\u00ae Corporation, the world\u2019s leading innovator and manufacturer of performance [&#8230;]<\/p>\n","protected":false},"author":8,"template":"","class_list":["post-63201","news","type-news","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Zinpro IsoFerm Wins Silver Medal at EuroTier Innovation Awards &#8211; Zinpro\u00ae<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.zinpro.com\/es_mx\/news\/zinpro-isoferm-wins-silver-medal-at-eurotier-innovation-awards\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Zinpro IsoFerm Wins Silver Medal at EuroTier Innovation Awards\" \/>\n<meta property=\"og:description\" content=\"Innovative product improves on-farm efficiency, profitability and sustainability.  EDEN PRAIRIE, Minn. \u2013 September 24, 2024 \u2013 Zinpro\u00ae Corporation, the world\u2019s leading innovator and manufacturer of performance [...]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.zinpro.com\/es_mx\/news\/zinpro-isoferm-wins-silver-medal-at-eurotier-innovation-awards\/\" \/>\n<meta property=\"og:site_name\" content=\"Zinpro\u00ae\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ZinproCorp\/\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@wdolezal\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.zinpro.com\\\/news\\\/zinpro-isoferm-wins-silver-medal-at-eurotier-innovation-awards\\\/\",\"url\":\"https:\\\/\\\/www.zinpro.com\\\/news\\\/zinpro-isoferm-wins-silver-medal-at-eurotier-innovation-awards\\\/\",\"name\":\"Zinpro IsoFerm Wins Silver Medal at EuroTier Innovation Awards &#8211; Zinpro\u00ae\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.zinpro.com\\\/#website\"},\"datePublished\":\"2024-09-24T10:00:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.zinpro.com\\\/news\\\/zinpro-isoferm-wins-silver-medal-at-eurotier-innovation-awards\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.zinpro.com\\\/news\\\/zinpro-isoferm-wins-silver-medal-at-eurotier-innovation-awards\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.zinpro.com\\\/news\\\/zinpro-isoferm-wins-silver-medal-at-eurotier-innovation-awards\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"News\",\"item\":\"https:\\\/\\\/www.zinpro.com\\\/news\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Zinpro IsoFerm Wins Silver Medal at EuroTier Innovation Awards\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.zinpro.com\\\/#website\",\"url\":\"https:\\\/\\\/www.zinpro.com\\\/\",\"name\":\"Zinpro\u00ae\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.zinpro.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Zinpro IsoFerm gana la Medalla de Plata en los Premios EuroTier a la Innovaci\u00f3n - Zinpro","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.zinpro.com\/es_mx\/news\/zinpro-isoferm-wins-silver-medal-at-eurotier-innovation-awards\/","og_locale":"es_MX","og_type":"article","og_title":"Zinpro IsoFerm Wins Silver Medal at EuroTier Innovation Awards","og_description":"Innovative product improves on-farm efficiency, profitability and sustainability.  EDEN PRAIRIE, Minn. \u2013 September 24, 2024 \u2013 Zinpro\u00ae Corporation, the world\u2019s leading innovator and manufacturer of performance [...]","og_url":"https:\/\/www.zinpro.com\/es_mx\/news\/zinpro-isoferm-wins-silver-medal-at-eurotier-innovation-awards\/","og_site_name":"Zinpro\u00ae","article_publisher":"https:\/\/www.facebook.com\/ZinproCorp\/","twitter_card":"summary_large_image","twitter_site":"@wdolezal","twitter_misc":{"Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.zinpro.com\/news\/zinpro-isoferm-wins-silver-medal-at-eurotier-innovation-awards\/","url":"https:\/\/www.zinpro.com\/news\/zinpro-isoferm-wins-silver-medal-at-eurotier-innovation-awards\/","name":"Zinpro IsoFerm gana la Medalla de Plata en los Premios EuroTier a la Innovaci\u00f3n - Zinpro","isPartOf":{"@id":"https:\/\/www.zinpro.com\/#website"},"datePublished":"2024-09-24T10:00:00+00:00","breadcrumb":{"@id":"https:\/\/www.zinpro.com\/news\/zinpro-isoferm-wins-silver-medal-at-eurotier-innovation-awards\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.zinpro.com\/news\/zinpro-isoferm-wins-silver-medal-at-eurotier-innovation-awards\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.zinpro.com\/news\/zinpro-isoferm-wins-silver-medal-at-eurotier-innovation-awards\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"News","item":"https:\/\/www.zinpro.com\/news\/"},{"@type":"ListItem","position":2,"name":"Zinpro IsoFerm Wins Silver Medal at EuroTier Innovation Awards"}]},{"@type":"WebSite","@id":"https:\/\/www.zinpro.com\/#website","url":"https:\/\/www.zinpro.com\/","name":"Zinpro","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.zinpro.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"spectra_custom_meta":{"_edit_lock":["1727204829:8"],"_edit_last":["8"],"ss_social_share_disable":[""],"_eb_reusable_block_ids":["a:0:{}"],"ss_ss_click_share_count_facebook":["2"],"ss_total_share_count":["0"],"_uag_css_file_name":["uag-css-63201.css"],"_uag_page_assets":["a:9:{s:3:\"css\";s:0:\"\";s:2:\"js\";s:0:\"\";s:18:\"current_block_list\";a:14:{i:0;s:14:\"core\/paragraph\";i:1;s:9:\"core\/list\";i:2;s:14:\"core\/list-item\";i:3;s:11:\"core\/search\";i:4;s:10:\"core\/group\";i:5;s:12:\"core\/heading\";i:6;s:17:\"core\/latest-posts\";i:7;s:20:\"core\/latest-comments\";i:8;s:13:\"core\/archives\";i:9;s:15:\"core\/categories\";i:10;s:17:\"core\/social-links\";i:11;s:16:\"core\/social-link\";i:12;s:11:\"core\/spacer\";i:13;s:10:\"core\/image\";}s:8:\"uag_flag\";b:0;s:11:\"uag_version\";s:10:\"1778690607\";s:6:\"gfonts\";a:0:{}s:10:\"gfonts_url\";s:0:\"\";s:12:\"gfonts_files\";a:0:{}s:14:\"uag_faq_layout\";b:0;}"]},"uagb_featured_image_src":[],"uagb_author_info":{"display_name":"Matt Wolleat","author_link":"https:\/\/www.zinpro.com\/es_mx\/resource-center\/author\/mwolleatzinpro-com\/"},"uagb_comment_info":0,"uagb_excerpt":"Innovative product improves on-farm efficiency, profitability and sustainability. EDEN PRAIRIE, Minn. \u2013 September 24, 2024 \u2013 Zinpro\u00ae Corporation, the world\u2019s leading innovator and manufacturer of performance [...]","_links":{"self":[{"href":"https:\/\/www.zinpro.com\/es_mx\/wp-json\/wp\/v2\/news\/63201","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.zinpro.com\/es_mx\/wp-json\/wp\/v2\/news"}],"about":[{"href":"https:\/\/www.zinpro.com\/es_mx\/wp-json\/wp\/v2\/types\/news"}],"author":[{"embeddable":true,"href":"https:\/\/www.zinpro.com\/es_mx\/wp-json\/wp\/v2\/users\/8"}],"version-history":[{"count":0,"href":"https:\/\/www.zinpro.com\/es_mx\/wp-json\/wp\/v2\/news\/63201\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.zinpro.com\/es_mx\/wp-json\/wp\/v2\/media?parent=63201"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}