

{"id":57131,"date":"2020-02-27T01:00:20","date_gmt":"2020-02-27T01:00:20","guid":{"rendered":"https:\/\/www.zinpro.com\/controlling-footpad-dermatitis-in-poultry\/"},"modified":"2023-07-19T13:10:08","modified_gmt":"2023-07-19T18:10:08","slug":"controlling-footpad-dermatitis-in-poultry","status":"publish","type":"post","link":"https:\/\/www.zinpro.com\/es_es\/resource-center\/blog\/controlling-footpad-dermatitis-in-poultry\/","title":{"rendered":"Control de la dermatitis podal en aves de corral"},"content":{"rendered":"<p>La dermatitis podal es un problema com\u00fan en la producci\u00f3n av\u00edcola, con tasas medias de prevalencia que a menudo rondan los 20%, pero que a veces alcanzan los 100% en algunas explotaciones av\u00edcolas. <\/p>\n\n\n\n<p>La dermatitis podal se caracteriza por la\np\u00e9rdida de integridad de la piel de la almohadilla plantar de un ave. Comienza como un desaf\u00edo qu\u00edmico\n- mec\u00e1nica, a menudo debida a condiciones de yacija h\u00fameda con altos niveles de pH\ny m\u00e1s tarde puede convertirse en un problema infeccioso. Cuando la almohadilla se da\u00f1a,\npuede abrir una cicatriz, que a su vez puede contaminarse con bacterias, dando lugar a una infecci\u00f3n secundaria que desencadena un proceso inflamatorio.\ninfecci\u00f3n secundaria, desencadenando una respuesta inflamatoria. <\/p>\n\n\n\n<p>Es importante tratar la dermatitis podal,\nespecialmente cuando las aves son j\u00f3venes, ya que su sistema inmunitario y la capa de queratina\nqueratina de sus almohadillas no est\u00e1n completamente desarrolladas y las\ncuraci\u00f3n de las lesiones. En algunos casos, las lesiones pueden no curarse nunca del todo. <\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-wet-litter-conditions-cause-footpad-dermatitis-in-poultry\">Las camas h\u00famedas provocan dermatitis podales en las aves de corral<\/h2>\n\n\n\n<p>La principal causa de dermatitis podal en las aves de corral es el amon\u00edaco presente en la yacija. Las condiciones de humedad de la yacija pueden aumentar la producci\u00f3n de amon\u00edaco, que puede crear un microambiente de alrededor de 11 pH en contacto directo con las patas. La cama es h\u00fameda por naturaleza, pero hay otros factores que pueden aumentar la producci\u00f3n de amon\u00edaco y contribuir a la dermatitis podal.&nbsp; <\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Los programas de nutrici\u00f3n av\u00edcola ricos en prote\u00ednas contribuyen a aumentar la excreci\u00f3n de nitr\u00f3geno, que posteriormente se convertir\u00e1 en amon\u00edaco en la yacija. <\/li>\n\n\n\n<li>Las dietas ricas en sodio o los niveles elevados de electrolitos tambi\u00e9n pueden provocar que la yacija se humedezca y, por tanto, una mayor producci\u00f3n de amon\u00edaco. <\/li>\n\n\n\n<li>Las altas densidades de poblaci\u00f3n pueden contribuir a humedecer la yacija y aumentar tambi\u00e9n el amon\u00edaco.<\/li>\n\n\n\n<li>Otros factores externos que pueden causar dermatitis podal son los bebederos con fugas o una ventilaci\u00f3n deficiente que no cree suficiente corriente de aire para mantener seca la yacija. <\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-visual-signs-of-footpad-dermatitis-in-poultry\">Signos visuales de la dermatitis podal en aves de corral<\/h2>\n\n\n\n<p>Cuando la dermatitis podal es grave, las aves\nse resisten a moverse debido al dolor. En otros casos, puede que tenga que levantar las\naves y examinarles las patas. Si tienen dermatitis podal, ver\u00e1 una cicatriz parecida a una costra seca, marr\u00f3n y negra.\nuna cicatriz parecida a una costra seca, marr\u00f3n y negra en la piel. Tambi\u00e9n es\ntambi\u00e9n es frecuente.&nbsp; <\/p>\n\n\n\n<p>La gravedad de la dermatitis podal puede determinarse\nmediante un sistema de puntuaci\u00f3n de las lesiones de la dermatitis podal. Los sistemas de puntuaci\u00f3n de las lesiones de dermatitis podal\ndermatitis podal var\u00edan en todo el mundo, pero la escala utilizada en Estados\nen los Estados Unidos es un sistema de 4 niveles: <\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>0 - Normal, sin lesi\u00f3n<\/li>\n\n\n\n<li>1 - Lesi\u00f3n leve<\/li>\n\n\n\n<li>2 - Lesi\u00f3n moderada<\/li>\n\n\n\n<li>3 - Lesi\u00f3n grave<\/li>\n<\/ul>\n\n\n\n<p>Las inspecciones de bienestar animal incluyen criterios similares.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-footpad-dermatitis-affects-wellness-and-performance-in-poultry\">La dermatitis podal afecta al bienestar y al rendimiento de las aves de corral<\/h2>\n\n\n\n<p>La dermatitis podal puede comenzar con un leve\npero a medida que la lesi\u00f3n se agrava y las bacterias penetran en la piel y causan una infecci\u00f3n secundaria, el dolor del ave puede aumentar.\nla piel y causan una infecci\u00f3n secundaria, el dolor del ave puede aumentar. Esto\nque las aves se muestren reacias a moverse y, en \u00faltima instancia, reduzcan la ingesta de alimento y agua.\ny agua. <\/p>\n\n\n\n<p>Los estudios de investigaci\u00f3n muestran que a medida que\nde la dermatitis podal, el \u00edndice de conversi\u00f3n alimenticia empeora. Las aves\nque sufren m\u00e1s dolor debido a la dermatitis podal, o a una infecci\u00f3n secundaria.\ninfecci\u00f3n secundaria, gastar\u00e1n m\u00e1s energ\u00eda y nutrientes para alimentar una respuesta\ninflamatoria para combatir la infecci\u00f3n y curar la lesi\u00f3n. Esto deja menos\nnutrientes y menos energ\u00eda disponible para que el ave la utilice para crecer y\ncrecimiento y desarrollo. Esta condici\u00f3n tambi\u00e9n se considera un indicador importante de\nbienestar.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-footpad-dermatitis-in-poultry-impacts-chicken-feet-export-industry\">La dermatitis podal de las aves de corral afecta a la industria exportadora de patas de pollo<\/h2>\n\n\n\n<p>En Estados Unidos, las patas de pollo suelen\nsubproducto, pero en los pa\u00edses asi\u00e1ticos son un manjar muy valioso.\nmuy valioso. <\/p>\n\n\n\n<p>Para que una pata de pollo sea apta para la exportaci\u00f3n\ndebe estar completamente limpia y sin lesiones de dermatitis podal bajo la\nla queratina. Incluso las pezu\u00f1as con lesiones leves o moderadas no ser\u00e1n aceptables para la exportaci\u00f3n.\naceptables para la exportaci\u00f3n. <\/p>\n\n\n\n<p>Si un ave ha tenido anteriormente\ndermatitis y la lesi\u00f3n se ha curado completamente, sus patas a\u00fan pueden ser\naceptables para la exportaci\u00f3n. Adem\u00e1s, las almohadillas plantares que tienen lesiones en la capa de queratina\npero est\u00e1n limpias una vez que se ha eliminado esa capa de queratina, tambi\u00e9n son aceptables. Este\nes importante prevenir la dermatitis podal desde una edad temprana.\n<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-performance-trace-minerals-to-manage-footpad-dermatitis\">Oligoelementos de alto rendimiento para tratar la dermatitis podal<\/h2>\n\n\n\n<p>Las c\u00e9lulas de la piel (queratinocitos) tienen una gran demanda\nde nutrientes debido a su elevada tasa de renovaci\u00f3n. Las dietas av\u00edcolas suelen proporcionar\nniveles adecuados de vitamina A y biotina, ambos importantes para la piel.\npiel. Sin embargo, el zinc, nutriente fundamental para la integridad y cicatrizaci\u00f3n de la piel, suele faltar porque no se absorbe f\u00e1cilmente.\nde f\u00e1cil absorci\u00f3n y requiere una fuente de alta calidad.\nalta calidad. <\/p>\n\n\n\n<p>Complementar su programa de nutrici\u00f3n av\u00edcola con 40 ppm de zinc procedente de <a href=\"\/es_es\/product\/zinpro-availa-zn\/\" target=\"_blank\" rel=\"noreferrer noopener\">Zinpro<sup>\u00ae<\/sup> Disponible en<sup>\u00ae<\/sup> Zn<\/a> puede aumentar la producci\u00f3n de queratina y reducir el impacto de la dermatitis podal en su reba\u00f1o. <\/p>\n\n\n\n<p>En un estudio, los oligoelementos de rendimiento\nredujeron la gravedad de las lesiones de dermatitis podal de una puntuaci\u00f3n media de 2,1\na 0,9 en aves expuestas a yacija h\u00fameda. Esto aument\u00f3 el n\u00famero de almohadillas\naceptables para la exportaci\u00f3n en 30%. <\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-proper-litter-management-for-controlling-footpad-dermatitis-in-poultry\">Manejo adecuado de la cama para controlar la dermatitis podal en aves de corral<\/h2>\n\n\n\n<p>La mejor manera de tratar la dermatitis podal es\nmediante una buena gesti\u00f3n de la yacija. Preste especial atenci\u00f3n al estado de\ncamada durante las tres primeras semanas de vida del reba\u00f1o, ya que desarrollan\nqueratina y una resistencia a la dermatitis podal. <\/p>\n\n\n\n<p>El lecho debe estar limpio y seco, con un\nespesor de al menos 2-3 pulgadas para absorber adecuadamente la humedad. Tambi\u00e9n debe\nmaterial que absorba mejor la humedad, como el heno o las virutas de\nmadera en lugar de c\u00e1scaras de arroz. Controle su lecho y aseg\u00farese de\nreemplazar el material cuando est\u00e9 demasiado h\u00famedo y no pueda absorber la humedad. <\/p>\n\n\n\n<p>Aseg\u00farese de que su gallinero tiene una ventilaci\u00f3n\nventilaci\u00f3n adecuada para mantener la cama seca. Adem\u00e1s, mantenga los bebederos en buenas condiciones y\ny aseg\u00farate de que no gotean y contribuyen a que el lecho est\u00e9 h\u00famedo. Enju\u00e1guelos y l\u00edmpielos\nantes de que entre una bandada en el gallinero. Aseg\u00farese de que todos\ny que la presi\u00f3n del agua no es demasiado alta. <\/p>\n\n\n\n<p><a href=\"https:\/\/www.zinpro.com\/es_es\/lets-connect\/\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\" (se abre en una nueva pesta\u00f1a)\">P\u00f3ngase en contacto con su representante de Zinpro hoy mismo<\/a> para saber m\u00e1s sobre c\u00f3mo complementar su programa de nutrici\u00f3n av\u00edcola con Availa-Zn.<\/p>","protected":false},"excerpt":{"rendered":"<p>La dermatitis podal en aves de corral es un problema com\u00fan en la industria av\u00edcola y puede provocar infecciones y dolor que reducen el crecimiento y la producci\u00f3n. Descubra c\u00f3mo una gesti\u00f3n adecuada y el uso de oligoelementos pueden ayudar a controlar la dermatitis podal en su explotaci\u00f3n av\u00edcola.<\/p>","protected":false},"author":33,"featured_media":57132,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_tec_requires_first_save":true,"_eb_attr":"","_uag_custom_page_level_css":"","_EventAllDay":false,"_EventTimezone":"","_EventStartDate":"","_EventEndDate":"","_EventStartDateUTC":"","_EventEndDateUTC":"","_EventShowMap":false,"_EventShowMapLink":false,"_EventURL":"","_EventCost":"","_EventCostDescription":"","_EventCurrencySymbol":"","_EventCurrencyCode":"","_EventCurrencyPosition":"","_EventDateTimeSeparator":"","_EventTimeRangeSeparator":"","_EventOrganizerID":[],"_EventVenueID":[],"_OrganizerEmail":"","_OrganizerPhone":"","_OrganizerWebsite":"","_VenueAddress":"","_VenueCity":"","_VenueCountry":"","_VenueProvince":"","_VenueState":"","_VenueZip":"","_VenuePhone":"","_VenueURL":"","_VenueStateProvince":"","_VenueLat":"","_VenueLng":"","_VenueShowMap":false,"_VenueShowMapLink":false,"_tribe_blocks_recurrence_rules":"","_tribe_blocks_recurrence_description":"","_tribe_blocks_recurrence_exclusions":"","_ecp_custom_2":"","footnotes":""},"categories":[2682],"tags":[2692,2696,2703,2688,2690],"species":[942],"class_list":["post-57131","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog","tag-animal-welfare","tag-epithelial-integrity","tag-food-safety","tag-gut-health","tag-lameness"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Controlling Footpad Dermatitis in Poultry &#8211; Zinpro\u00ae<\/title>\n<meta name=\"description\" content=\"posts from Zinpro\u00ae about Controlling Footpad Dermatitis in Poultry . Read more here.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.zinpro.com\/es_es\/resource-center\/blog\/controlling-footpad-dermatitis-in-poultry\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Controlling Footpad Dermatitis in Poultry &#8211; Zinpro\u00ae\" \/>\n<meta property=\"og:description\" content=\"posts from Zinpro\u00ae about Controlling Footpad Dermatitis in Poultry . Read more here.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.zinpro.com\/es_es\/resource-center\/blog\/controlling-footpad-dermatitis-in-poultry\/\" \/>\n<meta property=\"og:site_name\" content=\"Zinpro\u00ae\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ZinproCorp\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-02-27T01:00:20+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-07-19T18:10:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.zinpro.com\/wp-content\/uploads\/2023\/06\/Chick_in_litter_1200x600-3.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Dr. Marco Rebollo, DVM\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@wdolezal\" \/>\n<meta name=\"twitter:site\" content=\"@wdolezal\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Dr. Marco Rebollo, DVM\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.zinpro.com\\\/es_es\\\/resource-center\\\/blog\\\/controlling-footpad-dermatitis-in-poultry\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.zinpro.com\\\/es_es\\\/resource-center\\\/blog\\\/controlling-footpad-dermatitis-in-poultry\\\/\"},\"author\":{\"name\":\"Dr. Marco Rebollo, DVM\",\"@id\":\"https:\\\/\\\/www.zinpro.com\\\/#\\\/schema\\\/person\\\/063aabdb176a7b73ac35b99154792510\"},\"headline\":\"Controlling Footpad Dermatitis in Poultry\",\"datePublished\":\"2020-02-27T01:00:20+00:00\",\"dateModified\":\"2023-07-19T18:10:08+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.zinpro.com\\\/es_es\\\/resource-center\\\/blog\\\/controlling-footpad-dermatitis-in-poultry\\\/\"},\"wordCount\":979,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.zinpro.com\\\/es_es\\\/resource-center\\\/blog\\\/controlling-footpad-dermatitis-in-poultry\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.zinpro.com\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/Chick_in_litter_1200x600-3.jpg\",\"keywords\":[\"Animal Welfare\",\"Epithelial Integrity\",\"Food Safety\",\"Gut Health\",\"Lameness\"],\"articleSection\":[\"Blog\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.zinpro.com\\\/es_es\\\/resource-center\\\/blog\\\/controlling-footpad-dermatitis-in-poultry\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.zinpro.com\\\/es_es\\\/resource-center\\\/blog\\\/controlling-footpad-dermatitis-in-poultry\\\/\",\"url\":\"https:\\\/\\\/www.zinpro.com\\\/es_es\\\/resource-center\\\/blog\\\/controlling-footpad-dermatitis-in-poultry\\\/\",\"name\":\"Controlling Footpad Dermatitis in Poultry &#8211; Zinpro\u00ae\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.zinpro.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.zinpro.com\\\/es_es\\\/resource-center\\\/blog\\\/controlling-footpad-dermatitis-in-poultry\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.zinpro.com\\\/es_es\\\/resource-center\\\/blog\\\/controlling-footpad-dermatitis-in-poultry\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.zinpro.com\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/Chick_in_litter_1200x600-3.jpg\",\"datePublished\":\"2020-02-27T01:00:20+00:00\",\"dateModified\":\"2023-07-19T18:10:08+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.zinpro.com\\\/#\\\/schema\\\/person\\\/063aabdb176a7b73ac35b99154792510\"},\"description\":\"posts from Zinpro\u00ae about Controlling Footpad Dermatitis in Poultry . Read more here.\",\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.zinpro.com\\\/es_es\\\/resource-center\\\/blog\\\/controlling-footpad-dermatitis-in-poultry\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.zinpro.com\\\/es_es\\\/resource-center\\\/blog\\\/controlling-footpad-dermatitis-in-poultry\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.zinpro.com\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/Chick_in_litter_1200x600-3.jpg\",\"contentUrl\":\"https:\\\/\\\/www.zinpro.com\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/Chick_in_litter_1200x600-3.jpg\",\"width\":1200,\"height\":600,\"caption\":\"Chick standing in litter.\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.zinpro.com\\\/#website\",\"url\":\"https:\\\/\\\/www.zinpro.com\\\/\",\"name\":\"Zinpro\u00ae\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.zinpro.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.zinpro.com\\\/#\\\/schema\\\/person\\\/063aabdb176a7b73ac35b99154792510\",\"name\":\"Dr. Marco Rebollo, DVM\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.zinpro.com\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/MarcoRebollo-150x150-1.jpg\",\"url\":\"https:\\\/\\\/www.zinpro.com\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/MarcoRebollo-150x150-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.zinpro.com\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/MarcoRebollo-150x150-1.jpg\",\"caption\":\"Dr. Marco Rebollo, DVM\"},\"description\":\"Dr. Rebollo earned his doctoral degree in veterinary medicine from the National University of Mexico. He conducts research and provides poultry technical services to customers globally.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Control de la dermatitis podal en aves de corral - Zinpro\u00ae.","description":"posts de Zinpro\u00ae sobre el control de la dermatitis podal en aves de corral . Lea m\u00e1s aqu\u00ed.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.zinpro.com\/es_es\/resource-center\/blog\/controlling-footpad-dermatitis-in-poultry\/","og_locale":"es_ES","og_type":"article","og_title":"Controlling Footpad Dermatitis in Poultry &#8211; Zinpro\u00ae","og_description":"posts from Zinpro\u00ae about Controlling Footpad Dermatitis in Poultry . Read more here.","og_url":"https:\/\/www.zinpro.com\/es_es\/resource-center\/blog\/controlling-footpad-dermatitis-in-poultry\/","og_site_name":"Zinpro\u00ae","article_publisher":"https:\/\/www.facebook.com\/ZinproCorp\/","article_published_time":"2020-02-27T01:00:20+00:00","article_modified_time":"2023-07-19T18:10:08+00:00","og_image":[{"width":1200,"height":600,"url":"https:\/\/www.zinpro.com\/wp-content\/uploads\/2023\/06\/Chick_in_litter_1200x600-3.jpg","type":"image\/jpeg"}],"author":"Dr. Marco Rebollo, DVM","twitter_card":"summary_large_image","twitter_creator":"@wdolezal","twitter_site":"@wdolezal","twitter_misc":{"Escrito por":"Dr. Marco Rebollo, DVM","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.zinpro.com\/es_es\/resource-center\/blog\/controlling-footpad-dermatitis-in-poultry\/#article","isPartOf":{"@id":"https:\/\/www.zinpro.com\/es_es\/resource-center\/blog\/controlling-footpad-dermatitis-in-poultry\/"},"author":{"name":"Dr. Marco Rebollo, DVM","@id":"https:\/\/www.zinpro.com\/#\/schema\/person\/063aabdb176a7b73ac35b99154792510"},"headline":"Controlling Footpad Dermatitis in Poultry","datePublished":"2020-02-27T01:00:20+00:00","dateModified":"2023-07-19T18:10:08+00:00","mainEntityOfPage":{"@id":"https:\/\/www.zinpro.com\/es_es\/resource-center\/blog\/controlling-footpad-dermatitis-in-poultry\/"},"wordCount":979,"commentCount":0,"image":{"@id":"https:\/\/www.zinpro.com\/es_es\/resource-center\/blog\/controlling-footpad-dermatitis-in-poultry\/#primaryimage"},"thumbnailUrl":"https:\/\/www.zinpro.com\/wp-content\/uploads\/2023\/06\/Chick_in_litter_1200x600-3.jpg","keywords":["Animal Welfare","Epithelial Integrity","Food Safety","Gut Health","Lameness"],"articleSection":["Blog"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.zinpro.com\/es_es\/resource-center\/blog\/controlling-footpad-dermatitis-in-poultry\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.zinpro.com\/es_es\/resource-center\/blog\/controlling-footpad-dermatitis-in-poultry\/","url":"https:\/\/www.zinpro.com\/es_es\/resource-center\/blog\/controlling-footpad-dermatitis-in-poultry\/","name":"Control de la dermatitis podal en aves de corral - Zinpro\u00ae.","isPartOf":{"@id":"https:\/\/www.zinpro.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.zinpro.com\/es_es\/resource-center\/blog\/controlling-footpad-dermatitis-in-poultry\/#primaryimage"},"image":{"@id":"https:\/\/www.zinpro.com\/es_es\/resource-center\/blog\/controlling-footpad-dermatitis-in-poultry\/#primaryimage"},"thumbnailUrl":"https:\/\/www.zinpro.com\/wp-content\/uploads\/2023\/06\/Chick_in_litter_1200x600-3.jpg","datePublished":"2020-02-27T01:00:20+00:00","dateModified":"2023-07-19T18:10:08+00:00","author":{"@id":"https:\/\/www.zinpro.com\/#\/schema\/person\/063aabdb176a7b73ac35b99154792510"},"description":"posts de Zinpro\u00ae sobre el control de la dermatitis podal en aves de corral . Lea m\u00e1s aqu\u00ed.","inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.zinpro.com\/es_es\/resource-center\/blog\/controlling-footpad-dermatitis-in-poultry\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.zinpro.com\/es_es\/resource-center\/blog\/controlling-footpad-dermatitis-in-poultry\/#primaryimage","url":"https:\/\/www.zinpro.com\/wp-content\/uploads\/2023\/06\/Chick_in_litter_1200x600-3.jpg","contentUrl":"https:\/\/www.zinpro.com\/wp-content\/uploads\/2023\/06\/Chick_in_litter_1200x600-3.jpg","width":1200,"height":600,"caption":"Chick standing in litter."},{"@type":"WebSite","@id":"https:\/\/www.zinpro.com\/#website","url":"https:\/\/www.zinpro.com\/","name":"Zinpro","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.zinpro.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.zinpro.com\/#\/schema\/person\/063aabdb176a7b73ac35b99154792510","name":"Dr. Marco Rebollo, DVM","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.zinpro.com\/wp-content\/uploads\/2023\/06\/MarcoRebollo-150x150-1.jpg","url":"https:\/\/www.zinpro.com\/wp-content\/uploads\/2023\/06\/MarcoRebollo-150x150-1.jpg","contentUrl":"https:\/\/www.zinpro.com\/wp-content\/uploads\/2023\/06\/MarcoRebollo-150x150-1.jpg","caption":"Dr. Marco Rebollo, DVM"},"description":"El Dr. Rebollo se doctor\u00f3 en Medicina Veterinaria por la Universidad Nacional de M\u00e9xico. Realiza investigaciones y presta servicios t\u00e9cnicos av\u00edcolas a clientes de todo el mundo."}]}},"spectra_custom_meta":{"_wp_page_template":["default"],"_wpml_word_count":["{\"total\":1046,\"to_translate\":{\"pt-br\":1046,\"es\":1046,\"es_MX\":1046}}"],"_yoast_wpseo_primary_category":[""],"_wpml_media_duplicate":["1"],"_wpml_media_featured":["1"],"_yoast_wpseo_content_score":["90"],"_wpml_location_migration_done":["1"],"video_length":[""],"_video_length":[""],"_wpml_media_has_media":["1"],"_wp_old_date":[""],"ss_social_share_disable":[""],"_icl_lang_duplicate_of":[""],"_yoast_wpseo_estimated-reading-time-minutes":["5"],"_aioseop_description":["Footpad dermatitis in poultry, characterized as a loss of skin integrity of the footpad of a bird, can lead to secondary infection and inflammation. See how you can control footpad dermatitis with performance trace minerals."],"_aioseop_title":["Footpad Dermatitis in Poultry"],"_wp_old_slug":[""],"_wp_desired_post_slug":[""],"time_to_read":["5"],"_time_to_read":["field_64b80fae9ef9b"],"_wp_attachment_metadata":[""],"_last_translation_edit_mode":[""],"button":[""],"_button":[""],"searchable_keywords":[""],"_searchable_keywords":[""],"test_repeater":[""],"_test_repeater":[""],"_whp_hide_on_frontpage":[""],"_whp_hide_on_categories":[""],"_whp_hide_on_search":[""],"_whp_hide_on_tags":[""],"_whp_hide_on_authors":[""],"_whp_hide_in_rss_feed":[""],"_whp_hide_on_blog_page":[""],"_whp_hide_on_date":[""],"_whp_hide_on_post_navigation":[""],"_whp_hide_on_recent_posts":[""],"_whp_hide_on_archive":[""],"_whp_hide_on_rest_api":[""],"_whp_hide_on_single_post_page":[""],"_thumbnail_id":["57132"],"_edit_lock":["1774897448:14"],"_edit_last":["14"],"_yoast_wpseo_primary_species":["942"],"_yoast_wpseo_focuskeywords":["[]"],"_yoast_wpseo_keywordsynonyms":["[\"\"]"],"_yoast_wpseo_wordproof_timestamp":[""],"_eb_reusable_block_ids":["a:0:{}"],"_uag_css_file_name":["uag-css-57131.css"],"_uagb_previous_block_counts":["a:90:{s:21:\"uagb\/advanced-heading\";i:0;s:15:\"uagb\/blockquote\";i:0;s:12:\"uagb\/buttons\";i:0;s:18:\"uagb\/buttons-child\";i:0;s:19:\"uagb\/call-to-action\";i:0;s:15:\"uagb\/cf7-styler\";i:0;s:11:\"uagb\/column\";i:0;s:12:\"uagb\/columns\";i:0;s:14:\"uagb\/container\";i:0;s:21:\"uagb\/content-timeline\";i:0;s:27:\"uagb\/content-timeline-child\";i:0;s:14:\"uagb\/countdown\";i:0;s:12:\"uagb\/counter\";i:0;s:8:\"uagb\/faq\";i:0;s:14:\"uagb\/faq-child\";i:0;s:10:\"uagb\/forms\";i:0;s:17:\"uagb\/forms-accept\";i:0;s:19:\"uagb\/forms-checkbox\";i:0;s:15:\"uagb\/forms-date\";i:0;s:16:\"uagb\/forms-email\";i:0;s:17:\"uagb\/forms-hidden\";i:0;s:15:\"uagb\/forms-name\";i:0;s:16:\"uagb\/forms-phone\";i:0;s:16:\"uagb\/forms-radio\";i:0;s:17:\"uagb\/forms-select\";i:0;s:19:\"uagb\/forms-textarea\";i:0;s:17:\"uagb\/forms-toggle\";i:0;s:14:\"uagb\/forms-url\";i:0;s:14:\"uagb\/gf-styler\";i:0;s:15:\"uagb\/google-map\";i:0;s:11:\"uagb\/how-to\";i:0;s:16:\"uagb\/how-to-step\";i:0;s:9:\"uagb\/icon\";i:0;s:14:\"uagb\/icon-list\";i:0;s:20:\"uagb\/icon-list-child\";i:0;s:10:\"uagb\/image\";i:0;s:18:\"uagb\/image-gallery\";i:0;s:13:\"uagb\/info-box\";i:0;s:18:\"uagb\/inline-notice\";i:0;s:11:\"uagb\/lottie\";i:0;s:21:\"uagb\/marketing-button\";i:0;s:10:\"uagb\/modal\";i:0;s:18:\"uagb\/popup-builder\";i:0;s:16:\"uagb\/post-button\";i:0;s:18:\"uagb\/post-carousel\";i:0;s:17:\"uagb\/post-excerpt\";i:0;s:14:\"uagb\/post-grid\";i:0;s:15:\"uagb\/post-image\";i:0;s:17:\"uagb\/post-masonry\";i:0;s:14:\"uagb\/post-meta\";i:0;s:18:\"uagb\/post-taxonomy\";i:0;s:18:\"uagb\/post-timeline\";i:0;s:15:\"uagb\/post-title\";i:0;s:20:\"uagb\/restaurant-menu\";i:0;s:26:\"uagb\/restaurant-menu-child\";i:0;s:11:\"uagb\/review\";i:0;s:12:\"uagb\/section\";i:0;s:14:\"uagb\/separator\";i:0;s:11:\"uagb\/slider\";i:0;s:17:\"uagb\/slider-child\";i:0;s:17:\"uagb\/social-share\";i:0;s:23:\"uagb\/social-share-child\";i:0;s:16:\"uagb\/star-rating\";i:0;s:23:\"uagb\/sure-cart-checkout\";i:0;s:22:\"uagb\/sure-cart-product\";i:0;s:15:\"uagb\/sure-forms\";i:0;s:22:\"uagb\/table-of-contents\";i:0;s:9:\"uagb\/tabs\";i:0;s:15:\"uagb\/tabs-child\";i:0;s:18:\"uagb\/taxonomy-list\";i:0;s:9:\"uagb\/team\";i:0;s:16:\"uagb\/testimonial\";i:0;s:14:\"uagb\/wp-search\";i:0;s:19:\"uagb\/instagram-feed\";i:0;s:10:\"uagb\/login\";i:0;s:17:\"uagb\/loop-builder\";i:0;s:18:\"uagb\/loop-category\";i:0;s:20:\"uagb\/loop-pagination\";i:0;s:15:\"uagb\/loop-reset\";i:0;s:16:\"uagb\/loop-search\";i:0;s:14:\"uagb\/loop-sort\";i:0;s:17:\"uagb\/loop-wrapper\";i:0;s:13:\"uagb\/register\";i:0;s:19:\"uagb\/register-email\";i:0;s:24:\"uagb\/register-first-name\";i:0;s:23:\"uagb\/register-last-name\";i:0;s:22:\"uagb\/register-password\";i:0;s:30:\"uagb\/register-reenter-password\";i:0;s:19:\"uagb\/register-terms\";i:0;s:22:\"uagb\/register-username\";i:0;}"],"_uag_page_assets":["a:9:{s:3:\"css\";s:260:\".uag-blocks-common-selector{z-index:var(--z-index-desktop) !important}@media(max-width: 976px){.uag-blocks-common-selector{z-index:var(--z-index-tablet) !important}}@media(max-width: 767px){.uag-blocks-common-selector{z-index:var(--z-index-mobile) !important}}\";s:2:\"js\";s:0:\"\";s:18:\"current_block_list\";a:14:{i:0;s:14:\"core\/paragraph\";i:1;s:12:\"core\/heading\";i:2;s:9:\"core\/list\";i:3;s:14:\"core\/list-item\";i:4;s:11:\"core\/search\";i:5;s:10:\"core\/group\";i:6;s:17:\"core\/latest-posts\";i:7;s:20:\"core\/latest-comments\";i:8;s:13:\"core\/archives\";i:9;s:15:\"core\/categories\";i:10;s:17:\"core\/social-links\";i:11;s:16:\"core\/social-link\";i:12;s:11:\"core\/spacer\";i:13;s:10:\"core\/image\";}s:8:\"uag_flag\";b:0;s:11:\"uag_version\";s:10:\"1778690607\";s:6:\"gfonts\";a:0:{}s:10:\"gfonts_url\";s:0:\"\";s:12:\"gfonts_files\";a:0:{}s:14:\"uag_faq_layout\";b:0;}"]},"uagb_featured_image_src":{"full":["https:\/\/www.zinpro.com\/wp-content\/uploads\/2023\/06\/Chick_in_litter_1200x600-3.jpg",1200,600,false],"thumbnail":["https:\/\/www.zinpro.com\/wp-content\/uploads\/2023\/06\/Chick_in_litter_1200x600-3-150x150.jpg",150,150,true],"medium":["https:\/\/www.zinpro.com\/wp-content\/uploads\/2023\/06\/Chick_in_litter_1200x600-3-300x150.jpg",300,150,true],"medium_large":["https:\/\/www.zinpro.com\/wp-content\/uploads\/2023\/06\/Chick_in_litter_1200x600-3-768x384.jpg",640,320,true],"large":["https:\/\/www.zinpro.com\/wp-content\/uploads\/2023\/06\/Chick_in_litter_1200x600-3-1024x512.jpg",640,320,true],"gs-tiny":["https:\/\/www.zinpro.com\/wp-content\/uploads\/2023\/06\/Chick_in_litter_1200x600-3.jpg",50,25,false],"xl":["https:\/\/www.zinpro.com\/wp-content\/uploads\/2023\/06\/Chick_in_litter_1200x600-3.jpg",1200,600,false],"xxl":["https:\/\/www.zinpro.com\/wp-content\/uploads\/2023\/06\/Chick_in_litter_1200x600-3.jpg",1200,600,false],"xxxl":["https:\/\/www.zinpro.com\/wp-content\/uploads\/2023\/06\/Chick_in_litter_1200x600-3.jpg",1200,600,false],"xxxxl":["https:\/\/www.zinpro.com\/wp-content\/uploads\/2023\/06\/Chick_in_litter_1200x600-3.jpg",1200,600,false],"xxxxxl":["https:\/\/www.zinpro.com\/wp-content\/uploads\/2023\/06\/Chick_in_litter_1200x600-3.jpg",1200,600,false],"1536x1536":["https:\/\/www.zinpro.com\/wp-content\/uploads\/2023\/06\/Chick_in_litter_1200x600-3.jpg",1200,600,false],"2048x2048":["https:\/\/www.zinpro.com\/wp-content\/uploads\/2023\/06\/Chick_in_litter_1200x600-3.jpg",1200,600,false],"trp-custom-language-flag":["https:\/\/www.zinpro.com\/wp-content\/uploads\/2023\/06\/Chick_in_litter_1200x600-3-18x9.jpg",18,9,true],"gform-image-choice-sm":["https:\/\/www.zinpro.com\/wp-content\/uploads\/2023\/06\/Chick_in_litter_1200x600-3.jpg",300,150,false],"gform-image-choice-md":["https:\/\/www.zinpro.com\/wp-content\/uploads\/2023\/06\/Chick_in_litter_1200x600-3.jpg",400,200,false],"gform-image-choice-lg":["https:\/\/www.zinpro.com\/wp-content\/uploads\/2023\/06\/Chick_in_litter_1200x600-3.jpg",600,300,false],"menu-24x24":["https:\/\/www.zinpro.com\/wp-content\/uploads\/2023\/06\/Chick_in_litter_1200x600-3.jpg",24,12,false],"menu-36x36":["https:\/\/www.zinpro.com\/wp-content\/uploads\/2023\/06\/Chick_in_litter_1200x600-3.jpg",36,18,false],"menu-48x48":["https:\/\/www.zinpro.com\/wp-content\/uploads\/2023\/06\/Chick_in_litter_1200x600-3.jpg",48,24,false]},"uagb_author_info":{"display_name":"Dr. Marco Rebollo, DVM","author_link":"https:\/\/www.zinpro.com\/es_es\/resource-center\/author\/drmarcorebollo\/"},"uagb_comment_info":1,"uagb_excerpt":"Footpad dermatitis in poultry is a common problem in the poultry industry and can lead to infections and pain that reduce growth and production. Learn how proper management and performance trace minerals can help control footpad dermatitis on your poultry operation.","_links":{"self":[{"href":"https:\/\/www.zinpro.com\/es_es\/wp-json\/wp\/v2\/posts\/57131","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.zinpro.com\/es_es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.zinpro.com\/es_es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.zinpro.com\/es_es\/wp-json\/wp\/v2\/users\/33"}],"replies":[{"embeddable":true,"href":"https:\/\/www.zinpro.com\/es_es\/wp-json\/wp\/v2\/comments?post=57131"}],"version-history":[{"count":0,"href":"https:\/\/www.zinpro.com\/es_es\/wp-json\/wp\/v2\/posts\/57131\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.zinpro.com\/es_es\/wp-json\/wp\/v2\/media\/57132"}],"wp:attachment":[{"href":"https:\/\/www.zinpro.com\/es_es\/wp-json\/wp\/v2\/media?parent=57131"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.zinpro.com\/es_es\/wp-json\/wp\/v2\/categories?post=57131"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.zinpro.com\/es_es\/wp-json\/wp\/v2\/tags?post=57131"},{"taxonomy":"species","embeddable":true,"href":"https:\/\/www.zinpro.com\/es_es\/wp-json\/wp\/v2\/species?post=57131"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}