

{"id":55641,"date":"2023-06-08T17:50:33","date_gmt":"2023-06-08T17:50:33","guid":{"rendered":"https:\/\/www.zinpro.com\/?page_id=55641"},"modified":"2025-08-26T09:14:06","modified_gmt":"2025-08-26T14:14:06","slug":"our-history","status":"publish","type":"page","link":"https:\/\/www.zinpro.com\/es_es\/our-history\/","title":{"rendered":"Nuestra historia"},"content":{"rendered":"<div class=\"wp-block-group alignfull has-dark-gray-background-color has-background is-layout-constrained wp-block-group-is-layout-constrained\">\n<div class=\"wp-block-cover is-style-default\"><img loading=\"lazy\" decoding=\"async\" width=\"1280\" height=\"448\" class=\"wp-block-cover__image-background wp-image-55642\" alt=\"\" src=\"https:\/\/www.zinpro.com\/wp-content\/uploads\/2023\/06\/History-Hero.jpg\" data-object-fit=\"cover\" srcset=\"https:\/\/www.zinpro.com\/wp-content\/uploads\/2023\/06\/History-Hero.jpg 1280w, https:\/\/www.zinpro.com\/wp-content\/uploads\/2023\/06\/History-Hero-300x105.jpg 300w, https:\/\/www.zinpro.com\/wp-content\/uploads\/2023\/06\/History-Hero-1024x358.jpg 1024w, https:\/\/www.zinpro.com\/wp-content\/uploads\/2023\/06\/History-Hero-18x6.jpg 18w, https:\/\/www.zinpro.com\/wp-content\/uploads\/2023\/06\/History-Hero-768x269.jpg 768w\" sizes=\"auto, (max-width: 1280px) 100vw, 1280px\" \/><span aria-hidden=\"true\" class=\"wp-block-cover__background has-background-dim-0 has-background-dim\"><\/span><div class=\"wp-block-cover__inner-container is-layout-flow wp-block-cover-is-layout-flow\">\n<h1 class=\"wp-block-heading has-text-align-left has-white-color has-text-color\" id=\"h-our-history\">Nuestra historia<\/h1>\n<\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-group is-layout-constrained wp-block-group-is-layout-constrained\">\n<h2 class=\"wp-block-heading\" id=\"h-celebrating-50-years-of-innovation\">Celebramos 50 a\u00f1os de innovaci\u00f3n<\/h2>\n\n\n\n<p>En 2021 celebramos nuestro 50.\u00ba aniversario. Durante medio siglo, hemos sido la fuerza motriz que ha impulsado innumerables avances en materia de ciencia. Hemos experimentado un crecimiento exponencial y nos hemos posicionado como l\u00edderes en soluciones nutricionales integrales y probadas. Aunque estamos orgullosos de nuestro pasado, miramos con ilusi\u00f3n al futuro.&nbsp;&nbsp;<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-group alignfull has-light-gray-background-color has-background is-layout-constrained wp-block-group-is-layout-constrained\">\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\">\n<h3 class=\"wp-block-heading\" id=\"h-then-now-forward\">Pasado \u2022 Presente \u2022 Futuro<\/h3>\n\n\n\n<p>Cumplir 50 a\u00f1os es un logro importante. Partiendo de un origen humilde, hemos crecido hasta convertirnos en una empresa familiar con clientes y empleados de todo el mundo. Hoy celebramos este logro junto a todos vosotros. Estamos encantados de servir a quienes se esfuerzan por mejorar la vida de los animales y de las personas, para que prosperen y vivan lo mejor posible. Nos motiv\u00e1is a mejorar y ser m\u00e1s. Hemos conseguido este logro gracias a vuestro arduo trabajo y dedicaci\u00f3n. Todos nuestros clientes y empleados en todo el mundo forman parte del motivo de esta celebraci\u00f3n, as\u00ed como nuestra promesa de seguir comprometidos con vosotros durante los pr\u00f3ximos 50 a\u00f1os y muchos m\u00e1s.&nbsp;<\/p>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/www.zinpro.com\/wp-content\/uploads\/2025\/08\/Zinpro_BrandBrochure_082025.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">Descargar Folleto<\/a><\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\"><div class=\"epyt-video-wrapper\"><div  id=\"_ytid_37148\"  width=\"800\" height=\"450\"  data-origwidth=\"800\" data-origheight=\"450\" data-facadesrc=\"https:\/\/www.youtube.com\/embed\/fdo0xyEW20g?enablejsapi=1&#038;autoplay=0&#038;cc_load_policy=0&#038;cc_lang_pref=&#038;iv_load_policy=1&#038;loop=0&#038;rel=0&#038;fs=0&#038;playsinline=1&#038;autohide=2&#038;theme=dark&#038;color=red&#038;controls=1&#038;disablekb=0&#038;\" class=\"__youtube_prefs__ epyt-facade no-lazyload\" data-epautoplay=\"1\" ><img decoding=\"async\" data-spai-excluded=\"true\" class=\"epyt-facade-poster skip-lazy\" loading=\"lazy\"  alt=\"YouTube player\"  src=\"https:\/\/i.ytimg.com\/vi\/fdo0xyEW20g\/hqdefault.jpg\"  \/><button class=\"epyt-facade-play\" aria-label=\"Jugar\"><svg data-no-lazy=\"1\" height=\"100%\" version=\"1.1\" viewbox=\"0 0 68 48\" width=\"100%\"><path class=\"ytp-large-play-button-bg\" d=\"M66.52,7.74c-0.78-2.93-2.49-5.41-5.42-6.19C55.79,.13,34,0,34,0S12.21,.13,6.9,1.55 C3.97,2.33,2.27,4.81,1.48,7.74C0.06,13.05,0,24,0,24s0.06,10.95,1.48,16.26c0.78,2.93,2.49,5.41,5.42,6.19 C12.21,47.87,34,48,34,48s21.79-0.13,27.1-1.55c2.93-0.78,4.64-3.26,5.42-6.19C67.94,34.95,68,24,68,24S67.94,13.05,66.52,7.74z\" fill=\"#f00\"><\/path><path d=\"M 45,24 27,14 27,34\" fill=\"#fff\"><\/path><\/svg><\/button><\/div><\/div><\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-group is-layout-constrained wp-block-group-is-layout-constrained\">\n<h3 class=\"wp-block-heading\">M\u00e1s de 50 a\u00f1os de innovaci\u00f3n<\/h3>\n\n\n\n<p>En este medio siglo, hemos alcanzado muchos hitos. Eche un vistazo a lo que nos ha llevado al Zinpro\u00ae de hoy.<\/p>\n\n\n<div id=\"gutenslider-xh7mhbggc\" class=\"wp-block-eedee-block-gutenslider gs-frontend content-change alignnone arrow-style-1 arrow-position-sides arrow-mb-none arrows-lg arrows-md arrows-sm dot-style-1 dots-lg-none dots-md-none dots-sm-none dot-position-bottom history-slides is-position-top-center mb-none wrap-auto-height\" data-parallax-direction=\"down\" data-parallax-amount=\"1.3\" data-lg-transition=\"lg-slide\" data-hash=\"history-slides\" ><div class=\"eedee-swiper-outer\" style=\"--gutenslider-min-height: 50vh;--gutenslider-arrow-size: 52px;--gutenslider-dot-size: 25px;--gutenslider-arrow-color: #202020;--gutenslider-dot-color: #ffffff;--gutenslider-padding-y-mobile: 40px;--gutenslider-padding-x-mobile: 40px;--gutenslider-padding-y-tablet: 40px;--gutenslider-padding-x-tablet: 40px;--gutenslider-padding-y-desktop: 40px;--gutenslider-padding-x-desktop: 40px;--gutenslider-bg-image: url();--gutenslider-min-height-md: 50vh;--gutenslider-min-height-sm: 50vh;--gutenslider-padding-x: 0px;--gutenslider-padding-x-md: 40px;--gutenslider-padding-x-sm: 20px;--gutenslider-padding-y: 0px;--gutenslider-padding-y-md: 40px;--gutenslider-padding-y-sm: 20px;--gutenslider-arrow-size-md: 52px;--gutenslider-arrow-size-sm: 52px;--gutenslider-dot-size-md: 25px;--gutenslider-dot-size-sm: 25px;--gutenslider-arrow-bg-color: transparent;--gutenslider-arrow-hover-color: #eeeeee;--gutenslider-arrow-bg-hover-color: transparent;--gutenslider-arrow-x-offset: -66px;--gutenslider-arrow-x-offset-md: -66px;--gutenslider-arrow-x-offset-sm: -66px;--gutenslider-arrow-y-offset: 0px;--gutenslider-arrow-y-offset-md: 0px;--gutenslider-arrow-y-offset-sm: 0px;--gutenslider-arrow-x-spacing: 0px;--gutenslider-dot-y-offset: 10px;--gutenslider-dot-y-offset-md: 10px;--gutenslider-dot-y-offset-sm: 10px;--gutenslider-margin-x: 0px;--gutenslider-margin-x-md: 0px;--gutenslider-margin-x-sm: 0px;--gutenslider-margin-y: 30px;--gutenslider-margin-y-md: 30px;--gutenslider-margin-y-sm: 30px;--gutenslider-divider-top: 60px;--gutenslider-divider-bottom: 60px;--gutenslider-lightgallery-bg: #ffffff;--gutenslider-lightgallery-font: #000000;--gs-first-pos: 50% 50%;--gs-gap-vertical: var( --wp--style--gallery-gap-default, var( --gallery-block--gutter-size, var( --wp--style--block-gap, 0.5em ) ) );--gs-gap-horizontal: var( --wp--style--gallery-gap-default, var( --gallery-block--gutter-size, var( --wp--style--block-gap, 0.5em ) ) );\"><div class=\"gutenslider-divider-top\" style=\"color:#fff;\"><\/div><div class=\"swiper\" data-settings='{\"autoplay\":false,\"speed\":700,\"direction\":\"horizontal\",\"autoHeight\":\"\",\"loop\":false,\"centeredSlides\":false,\"spaceBetween\":20,\"slidesPerView\":1,\"slidesPerGroup\":1,\"effect\":\"slide\",\"coverflowEffect\":{\"rotate\":30,\"slideShadows\":false,\"depth\":100,\"stretch\":50,\"modifier\":1},\"fadeEffect\":{\"crossFade\":true},\"zoom\":\"\",\"navigation\":{\"nextEl\":\"#gutenslider-xh7mhbggc .eedee-gutenslider-next\",\"prevEl\":\"#gutenslider-xh7mhbggc .eedee-gutenslider-prev\"},\"pagination\":{\"type\":\"bullets\",\"clickable\":true,\"dynamicBullets\":false,\"el\":\"#gutenslider-xh7mhbggc .eedee-gutenslider-pagination\"},\"pauseOnHover\":\"1\",\"watchSlidesProgress\":true,\"watchSlidesVisibility\":true,\"settingsMd\":{\"autoHeight\":\"\",\"slidesPerView\":1,\"slidesPerGroup\":1,\"spaceBetween\":20,\"loop\":false},\"settingsLg\":{\"autoHeight\":\"\",\"slidesPerView\":3.4,\"slidesPerGroup\":1,\"spaceBetween\":20,\"loop\":false},\"hasLg\":false,\"hasLgCounter\":true,\"isFullScreen\":false,\"arrowsFollowMouse\":false,\"lgTitle\":\"none\",\"lgCaption\":\"none\",\"lgThumbnails\":true,\"lgZoomEnabled\":false,\"keyboard\":{\"keyboard\":{\"enabled\":true,\"onlyInViewport\":true}},\"hashNavigation\":{\"replaceState\":true,\"watchState\":true},\"dividers\":false}'><div class=\"swiper-wrapper\">\n<div class=\"swiper-slide wp-block-eedee-block-gutenslide is-position-top-center ed-bg-none\" style=\"--slide-min-width:80%;\" data-hash=\"\"><div class=\"eedee-background-div no-media-background\"><div class=\"eedee-background-div__overlay\" style=\"opacity:1;\"><\/div><\/div><div class=\"slide-content\">\n\n\n<div id=\"history-slide-block_240d5a8810d60c616be3c937e211ebea\" class=\"module history-slide-block block-has-img\" block-data-decade=\"1960\">\n\t<div class=\"history-slide-block-top\">\n\t\t\t\t<figure>\n\t\t\t<img decoding=\"async\" src=\"https:\/\/www.zinpro.com\/wp-content\/uploads\/2023\/07\/OurHistory-DeanAnderson.jpeg\" alt=\"Dean Anderson\" \/>\n\t\t<\/figure>\n\t\t\t\t<span class=\"year\">1960<\/span>\n\t<\/div>\n\t<div class=\"history-slide-block-bottom\">\n\t\t<p>Dean Anderson crea su primer producto en casa, haciendo realidad su sue\u00f1o visionario de utilizar el zinc para mejorar la nutrici\u00f3n animal.<\/p>\n\t<\/div>\n<\/div>\n\n<\/div><\/div>\n\n<div class=\"swiper-slide wp-block-eedee-block-gutenslide is-position-top-center ed-bg-none\" style=\"--slide-min-width:80%;\" data-hash=\"\"><div class=\"eedee-background-div no-media-background\"><div class=\"eedee-background-div__overlay\" style=\"opacity:1;\"><\/div><\/div><div class=\"slide-content\">\n\n\n<div id=\"history-slide-block_202cd4eec38f0a32d2408efded25ac7d\" class=\"module history-slide-block no-img\" block-data-decade=\"1960\">\n\t<div class=\"history-slide-block-top\">\n\t\t\t\t<span class=\"year\">1965<\/span>\n\t<\/div>\n\t<div class=\"history-slide-block-bottom\">\n\t\t<p>Zinpro Corporation se funda en Iowa dando paso a d\u00e9cadas de crecimiento sostenido gracias a su compromiso con la calidad de sus productos, la calidad de su personal y su concentraci\u00f3n en una sola cosa: la nutrici\u00f3n mineral traza.<\/p>\n\t<\/div>\n<\/div>\n\n<\/div><\/div>\n\n<div class=\"swiper-slide wp-block-eedee-block-gutenslide is-position-top-center ed-bg-none\" style=\"--slide-min-width:80%;\" data-hash=\"\"><div class=\"eedee-background-div no-media-background\"><div class=\"eedee-background-div__overlay\" style=\"opacity:1;\"><\/div><\/div><div class=\"slide-content\">\n\n\n<div id=\"history-slide-block_b6c6d4e483de9d7c88967c9411f2984a\" class=\"module history-slide-block block-has-img\" block-data-decade=\"1970\">\n\t<div class=\"history-slide-block-top\">\n\t\t\t\t<figure>\n\t\t\t<img decoding=\"async\" src=\"https:\/\/www.zinpro.com\/wp-content\/uploads\/2023\/07\/OurHistory-Zinpro40-440x280-1.jpeg\" alt=\"Founders Dean and Mary Anderson officially incorporate Zinpro in 1971\" \/>\n\t\t<\/figure>\n\t\t\t\t<span class=\"year\">1971<\/span>\n\t<\/div>\n\t<div class=\"history-slide-block-bottom\">\n\t\t<p>Los fundadores Dean y Mary Anderson constituyen oficialmente Zinpro en Excelsior, Minnesota, comercializando su primer producto Zinpro\u00ae Performance Minerals\u00ae: ZINPRO\u00ae 40 (zinc-metionina ZINPRO).<\/p>\n\t<\/div>\n<\/div>\n\n<\/div><\/div>\n\n<div class=\"swiper-slide wp-block-eedee-block-gutenslide is-position-top-center ed-bg-none\" style=\"--slide-min-width:80%;\" data-hash=\"\"><div class=\"eedee-background-div no-media-background\"><div class=\"eedee-background-div__overlay\" style=\"opacity:1;\"><\/div><\/div><div class=\"slide-content\">\n\n\n<div id=\"history-slide-block_51c4fe901ae8937414dcc9949f7144cb\" class=\"module history-slide-block no-img\" block-data-decade=\"1970\">\n\t<div class=\"history-slide-block-top\">\n\t\t\t\t<span class=\"year\">1976<\/span>\n\t<\/div>\n\t<div class=\"history-slide-block-bottom\">\n\t\t<p>Zinpro\u00ae 200 zinc metionina y METH-IRON 65 metionina f\u00e9rrica se unen a la l\u00ednea original de complejos minerales traza de Zinpro.<\/p>\n\t<\/div>\n<\/div>\n\n<\/div><\/div>\n\n<div class=\"swiper-slide wp-block-eedee-block-gutenslide is-position-top-center ed-bg-none\" style=\"--slide-min-width:80%;\" data-hash=\"\"><div class=\"eedee-background-div no-media-background\"><div class=\"eedee-background-div__overlay\" style=\"opacity:1;\"><\/div><\/div><div class=\"slide-content\">\n\n\n<div id=\"history-slide-block_5280baa2c9f7b56bc1eb67dbe4fa737f\" class=\"module history-slide-block block-has-img\" block-data-decade=\"1980\">\n\t<div class=\"history-slide-block-top\">\n\t\t\t\t<figure>\n\t\t\t<img decoding=\"async\" src=\"https:\/\/www.zinpro.com\/wp-content\/uploads\/2023\/07\/OurHistory-Mexico-440x513-1.jpeg\" alt=\"Zinpro Mexico regional office\" \/>\n\t\t<\/figure>\n\t\t\t\t<span class=\"year\">1982<\/span>\n\t<\/div>\n\t<div class=\"history-slide-block-bottom\">\n\t\t<p>Zinpro abre su oficina regional en M\u00e9xico.<\/p>\n<p>Zinpro<sup>\u00ae<\/sup> 100, que completa la l\u00ednea de productos de zinc-metionina.<\/p>\n\t<\/div>\n<\/div>\n\n<\/div><\/div>\n\n<div class=\"swiper-slide wp-block-eedee-block-gutenslide is-position-top-center ed-bg-none\" style=\"--slide-min-width:80%;\" data-hash=\"\"><div class=\"eedee-background-div no-media-background\"><div class=\"eedee-background-div__overlay\" style=\"opacity:1;\"><\/div><\/div><div class=\"slide-content\">\n\n\n<div id=\"history-slide-block_99ac2e1e16a440786bbc077f86f38f1a\" class=\"module history-slide-block no-img\" block-data-decade=\"1980\">\n\t<div class=\"history-slide-block-top\">\n\t\t\t\t<span class=\"year\">1986<\/span>\n\t<\/div>\n\t<div class=\"history-slide-block-bottom\">\n\t\t<p>Se presenta el primer producto de manganeso de Zinpro, la metionina de manganeso Zinpro\u00ae MANPRO\u00ae.<\/p>\n\t<\/div>\n<\/div>\n\n<\/div><\/div>\n\n<div class=\"swiper-slide wp-block-eedee-block-gutenslide is-position-top-center ed-bg-none\" style=\"--slide-min-width:80%;\" data-hash=\"\"><div class=\"eedee-background-div no-media-background\"><div class=\"eedee-background-div__overlay\" style=\"opacity:1;\"><\/div><\/div><div class=\"slide-content\">\n\n\n<div id=\"history-slide-block_830f6c5d141e6cd503db2ae2fef11c6f\" class=\"module history-slide-block block-has-img\" block-data-decade=\"1990\">\n\t<div class=\"history-slide-block-top\">\n\t\t\t\t<figure>\n\t\t\t<img decoding=\"async\" src=\"https:\/\/www.zinpro.com\/wp-content\/uploads\/2023\/07\/OurHistory-Australia-440x280-1.jpeg\" alt=\"Zinpro Ocenia regional office\" \/>\n\t\t<\/figure>\n\t\t\t\t<span class=\"year\">1991<\/span>\n\t<\/div>\n\t<div class=\"history-slide-block-bottom\">\n\t\t<p>Zinpro abre su oficina regional en Ocean\u00eda.<\/p>\n\t<\/div>\n<\/div>\n\n<\/div><\/div>\n\n<div class=\"swiper-slide wp-block-eedee-block-gutenslide is-position-top-center ed-bg-none\" style=\"--slide-min-width:80%;\" data-hash=\"\"><div class=\"eedee-background-div no-media-background\"><div class=\"eedee-background-div__overlay\" style=\"opacity:1;\"><\/div><\/div><div class=\"slide-content\">\n\n\n<div id=\"history-slide-block_522db2237d7f1136d123d88c7e5a645f\" class=\"module history-slide-block block-has-img\" block-data-decade=\"1990\">\n\t<div class=\"history-slide-block-top\">\n\t\t\t\t<figure>\n\t\t\t<img decoding=\"async\" src=\"https:\/\/www.zinpro.com\/wp-content\/uploads\/2023\/07\/OurHistory-Garner-440x280-1.jpeg\" alt=\"Zinpro manufacturing facility in Garner, Iowa\" \/>\n\t\t<\/figure>\n\t\t\t\t<span class=\"year\">1993<\/span>\n\t<\/div>\n\t<div class=\"history-slide-block-bottom\">\n\t\t<p>Se construye la primera planta de fabricaci\u00f3n de Zinpro en Garner, Iowa.<\/p>\n\t<\/div>\n<\/div>\n\n<\/div><\/div>\n\n<div class=\"swiper-slide wp-block-eedee-block-gutenslide is-position-top-center ed-bg-none\" style=\"--slide-min-width:80%;\" data-hash=\"\"><div class=\"eedee-background-div no-media-background\"><div class=\"eedee-background-div__overlay\" style=\"opacity:1;\"><\/div><\/div><div class=\"slide-content\">\n\n\n<div id=\"history-slide-block_a732c034f166eea1cac48d61edf0ca62\" class=\"module history-slide-block block-has-img\" block-data-decade=\"1990\">\n\t<div class=\"history-slide-block-top\">\n\t\t\t\t<figure>\n\t\t\t<img decoding=\"async\" src=\"https:\/\/www.zinpro.com\/wp-content\/uploads\/2023\/07\/OurHistory-AvailaZn.jpeg\" alt=\"Zinpro Availa\" \/>\n\t\t<\/figure>\n\t\t\t\t<span class=\"year\">1996<\/span>\n\t<\/div>\n\t<div class=\"history-slide-block-bottom\">\n\t\t<p>En el 25\u00ba aniversario se presenta al mundo Zinpro\u00ae Availa\u00ae, una l\u00ednea de complejos de amino\u00e1cidos \u00fanica en el mercado.<\/p>\n<p>Zinpro abre oficinas regionales en Europa y Jap\u00f3n.<\/p>\n\t<\/div>\n<\/div>\n\n<\/div><\/div>\n\n<div class=\"swiper-slide wp-block-eedee-block-gutenslide is-position-top-center ed-bg-none\" style=\"--slide-min-width:80%;\" data-hash=\"\"><div class=\"eedee-background-div no-media-background\"><div class=\"eedee-background-div__overlay\" style=\"opacity:1;\"><\/div><\/div><div class=\"slide-content\">\n\n\n<div id=\"history-slide-block_85e72a601159e14d0fe82515a600b850\" class=\"module history-slide-block block-has-img\" block-data-decade=\"1990\">\n\t<div class=\"history-slide-block-top\">\n\t\t\t\t<figure>\n\t\t\t<img decoding=\"async\" src=\"https:\/\/www.zinpro.com\/wp-content\/uploads\/2023\/07\/MikeAnderson768x896.jpeg\" alt=\"Zinpro founder Dean Anderson\" \/>\n\t\t<\/figure>\n\t\t\t\t<span class=\"year\">1999<\/span>\n\t<\/div>\n\t<div class=\"history-slide-block-bottom\">\n\t\t<p>La Fundaci\u00f3n Anderson se crea en reconocimiento al esp\u00edritu humano y generoso de Dean y Mary Anderson.<\/p>\n\t<\/div>\n<\/div>\n\n<\/div><\/div>\n\n<div class=\"swiper-slide wp-block-eedee-block-gutenslide is-position-top-center ed-bg-none\" style=\"--slide-min-width:80%;\" data-hash=\"\"><div class=\"eedee-background-div no-media-background\"><div class=\"eedee-background-div__overlay\" style=\"opacity:1;\"><\/div><\/div><div class=\"slide-content\">\n\n\n<div id=\"history-slide-block_e7a4e4c7ec951b667aaeb1bbbf501a9d\" class=\"module history-slide-block block-has-img\" block-data-decade=\"1990\">\n\t<div class=\"history-slide-block-top\">\n\t\t\t\t<figure>\n\t\t\t<img decoding=\"async\" src=\"https:\/\/www.zinpro.com\/wp-content\/uploads\/2023\/07\/OurHistory-China-440x513-1.jpeg\" alt=\"Zinpro regional offices\" \/>\n\t\t<\/figure>\n\t\t\t\t<span class=\"year\">1999<\/span>\n\t<\/div>\n\t<div class=\"history-slide-block-bottom\">\n\t\t<p>Zinpro abre dos oficinas regionales m\u00e1s, una en China y otra en Sudam\u00e9rica.<\/p>\n\t<\/div>\n<\/div>\n\n<\/div><\/div>\n\n<div class=\"swiper-slide wp-block-eedee-block-gutenslide is-position-top-center ed-bg-none\" style=\"--slide-min-width:80%;\" data-hash=\"\"><div class=\"eedee-background-div no-media-background\"><div class=\"eedee-background-div__overlay\" style=\"opacity:1;\"><\/div><\/div><div class=\"slide-content\">\n\n\n<div id=\"history-slide-block_5663d910c33cf43eccf42eb267aea2ec\" class=\"module history-slide-block block-has-img\" block-data-decade=\"2000\">\n\t<div class=\"history-slide-block-top\">\n\t\t\t\t<figure>\n\t\t\t<img decoding=\"async\" src=\"https:\/\/www.zinpro.com\/wp-content\/uploads\/2023\/07\/OurHistory-NorthBranch-440x280-1.jpeg\" alt=\"Zinpro manufacturing facility in North Branch, Minnesota\" \/>\n\t\t<\/figure>\n\t\t\t\t<span class=\"year\">2000<\/span>\n\t<\/div>\n\t<div class=\"history-slide-block-bottom\">\n\t\t<p>Zinpro abre una segunda planta de fabricaci\u00f3n en North Branch, Minnesota, as\u00ed como una nueva sede mundial en Eden Prairie, Minnesota.<\/p>\n\t<\/div>\n<\/div>\n\n<\/div><\/div>\n\n<div class=\"swiper-slide wp-block-eedee-block-gutenslide is-position-top-center ed-bg-none\" style=\"--slide-min-width:80%;\" data-hash=\"\"><div class=\"eedee-background-div no-media-background\"><div class=\"eedee-background-div__overlay\" style=\"opacity:1;\"><\/div><\/div><div class=\"slide-content\">\n\n\n<div id=\"history-slide-block_1932efc68141b40e8adf5e17aa6461a1\" class=\"module history-slide-block block-has-img\" block-data-decade=\"2000\">\n\t<div class=\"history-slide-block-top\">\n\t\t\t\t<figure>\n\t\t\t<img decoding=\"async\" src=\"https:\/\/www.zinpro.com\/wp-content\/uploads\/2023\/07\/Locations-Thailand-320x240-1.jpeg\" alt=\"Zinpro regional office in Thailand\" \/>\n\t\t<\/figure>\n\t\t\t\t<span class=\"year\">2001<\/span>\n\t<\/div>\n\t<div class=\"history-slide-block-bottom\">\n\t\t<p>Zinpro abre una nueva oficina regional en Tailandia.<\/p>\n\t<\/div>\n<\/div>\n\n<\/div><\/div>\n\n<div class=\"swiper-slide wp-block-eedee-block-gutenslide is-position-top-center ed-bg-none\" style=\"--slide-min-width:80%;\" data-hash=\"\"><div class=\"eedee-background-div no-media-background\"><div class=\"eedee-background-div__overlay\" style=\"opacity:1;\"><\/div><\/div><div class=\"slide-content\">\n\n\n<div id=\"history-slide-block_912ba755e3d718f79ed45d77f610ee1e\" class=\"module history-slide-block block-has-img\" block-data-decade=\"2000\">\n\t<div class=\"history-slide-block-top\">\n\t\t\t\t<figure>\n\t\t\t<img decoding=\"async\" src=\"https:\/\/www.zinpro.com\/wp-content\/uploads\/2023\/07\/OurHistory-DairyLocomotion-440x513-1.jpeg\" alt=\"Dairy cow with farmer\" \/>\n\t\t<\/figure>\n\t\t\t\t<span class=\"year\">2001<\/span>\n\t<\/div>\n\t<div class=\"history-slide-block-bottom\">\n\t\t<p>Se presenta el innovador sistema de locomoci\u00f3n del ganado lechero Zinpro.<\/p>\n\t<\/div>\n<\/div>\n\n<\/div><\/div>\n\n<div class=\"swiper-slide wp-block-eedee-block-gutenslide is-position-top-center ed-bg-none\" style=\"--slide-min-width:80%;\" data-hash=\"\"><div class=\"eedee-background-div no-media-background\"><div class=\"eedee-background-div__overlay\" style=\"opacity:1;\"><\/div><\/div><div class=\"slide-content\">\n\n\n<div id=\"history-slide-block_1785c9c628c24f29258c462d024e121f\" class=\"module history-slide-block block-has-img\" block-data-decade=\"2000\">\n\t<div class=\"history-slide-block-top\">\n\t\t\t\t<figure>\n\t\t\t<img decoding=\"async\" src=\"https:\/\/www.zinpro.com\/wp-content\/uploads\/2023\/07\/OurHistory-MENA-440x513-1.jpeg\" alt=\"Zinpro office in Amman, Jordan\" \/>\n\t\t<\/figure>\n\t\t\t\t<span class=\"year\">2004<\/span>\n\t<\/div>\n\t<div class=\"history-slide-block-bottom\">\n\t\t<p>Zinpro abre una oficina en Amm\u00e1n (Jordania) para ampliar el negocio en la regi\u00f3n de Oriente Pr\u00f3ximo y Norte de \u00c1frica (MENA).<\/p>\n\t<\/div>\n<\/div>\n\n<\/div><\/div>\n\n<div class=\"swiper-slide wp-block-eedee-block-gutenslide is-position-top-center ed-bg-none\" style=\"--slide-min-width:80%;\" data-hash=\"\"><div class=\"eedee-background-div no-media-background\"><div class=\"eedee-background-div__overlay\" style=\"opacity:1;\"><\/div><\/div><div class=\"slide-content\">\n\n\n<div id=\"history-slide-block_b91674bdba80b4f22d98d3402dc6588c\" class=\"module history-slide-block block-has-img\" block-data-decade=\"2000\">\n\t<div class=\"history-slide-block-top\">\n\t\t\t\t<figure>\n\t\t\t<img decoding=\"async\" src=\"https:\/\/www.zinpro.com\/wp-content\/uploads\/2023\/07\/OurHistory-5Rs-440x280-1.jpeg\" alt=\"\" \/>\n\t\t<\/figure>\n\t\t\t\t<span class=\"year\">2005<\/span>\n\t<\/div>\n\t<div class=\"history-slide-block-bottom\">\n\t\t<p>Zinpro establece los criterios de las 5 R's-Performance Mineral Essential: Retorno, Respuesta, Repetibilidad, Investigaci\u00f3n y Tranquilidad.<\/p>\n\t<\/div>\n<\/div>\n\n<\/div><\/div>\n\n<div class=\"swiper-slide wp-block-eedee-block-gutenslide is-position-top-center ed-bg-none\" style=\"--slide-min-width:80%;\" data-hash=\"\"><div class=\"eedee-background-div no-media-background\"><div class=\"eedee-background-div__overlay\" style=\"opacity:1;\"><\/div><\/div><div class=\"slide-content\">\n\n\n<div id=\"history-slide-block_12d926b5db0bdea8a91e638d57ebe79d\" class=\"module history-slide-block block-has-img\" block-data-decade=\"2000\">\n\t<div class=\"history-slide-block-top\">\n\t\t\t\t<figure>\n\t\t\t<img decoding=\"async\" src=\"https:\/\/www.zinpro.com\/wp-content\/uploads\/2023\/07\/OurHistory-SowLamenessSymposium-440x280-1.jpeg\" alt=\"\" \/>\n\t\t<\/figure>\n\t\t\t\t<span class=\"year\">2008<\/span>\n\t<\/div>\n\t<div class=\"history-slide-block-bottom\">\n\t\t<p>Zinpro organiza el primer simposio mundial sobre cojeras de cerdas en Minneapolis, con simposios adicionales en Brasil y Tailandia.<\/p>\n<p>Zinpro completa la ampliaci\u00f3n de su planta de fabricaci\u00f3n de Garner, Iowa.<\/p>\n\t<\/div>\n<\/div>\n\n<\/div><\/div>\n\n<div class=\"swiper-slide wp-block-eedee-block-gutenslide is-position-top-center ed-bg-none\" style=\"--slide-min-width:80%;\" data-hash=\"\"><div class=\"eedee-background-div no-media-background\"><div class=\"eedee-background-div__overlay\" style=\"opacity:1;\"><\/div><\/div><div class=\"slide-content\">\n\n\n<div id=\"history-slide-block_445272cc4b6ab80ee8de023be1fd78ce\" class=\"module history-slide-block block-has-img\" block-data-decade=\"2000\">\n\t<div class=\"history-slide-block-top\">\n\t\t\t\t<figure>\n\t\t\t<img decoding=\"async\" src=\"https:\/\/www.zinpro.com\/wp-content\/uploads\/2023\/07\/OurHistory-FirstStep-440x280-1.jpeg\" alt=\"\" \/>\n\t\t<\/figure>\n\t\t\t\t<span class=\"year\">2009<\/span>\n\t<\/div>\n\t<div class=\"history-slide-block-bottom\">\n\t\t<p>Zinpro lanza su Programa de Evaluaci\u00f3n y Prevenci\u00f3n de Cojeras Zinpro\u00ae FirstStep\u00ae, que proporciona una evaluaci\u00f3n completa de los factores de riesgo de cojera en una explotaci\u00f3n lechera.<\/p>\n\t<\/div>\n<\/div>\n\n<\/div><\/div>\n\n<div class=\"swiper-slide wp-block-eedee-block-gutenslide is-position-top-center ed-bg-none\" style=\"--slide-min-width:80%;\" data-hash=\"\"><div class=\"eedee-background-div no-media-background\"><div class=\"eedee-background-div__overlay\" style=\"opacity:1;\"><\/div><\/div><div class=\"slide-content\">\n\n\n<div id=\"history-slide-block_f5aaa0cc5f6e14547ad3f83f60e3f303\" class=\"module history-slide-block block-has-img\" block-data-decade=\"2010\">\n\t<div class=\"history-slide-block-top\">\n\t\t\t\t<figure>\n\t\t\t<img decoding=\"async\" src=\"https:\/\/www.zinpro.com\/wp-content\/uploads\/2023\/07\/OurHistory-StepUp-440x280-1.jpeg\" alt=\"\" \/>\n\t\t<\/figure>\n\t\t\t\t<span class=\"year\">2013<\/span>\n\t<\/div>\n\t<div class=\"history-slide-block-bottom\">\n\t\t<p>Zinpro presenta el programa de gesti\u00f3n de cojeras Zinpro\u00ae Step Up\u00ae.<\/p>\n<p>Zinpro abre una planta de fabricaci\u00f3n en Shell Rock, Iowa.<\/p>\n\t<\/div>\n<\/div>\n\n<\/div><\/div>\n\n<div class=\"swiper-slide wp-block-eedee-block-gutenslide is-position-top-center ed-bg-none\" style=\"--slide-min-width:80%;\" data-hash=\"\"><div class=\"eedee-background-div no-media-background\"><div class=\"eedee-background-div__overlay\" style=\"opacity:1;\"><\/div><\/div><div class=\"slide-content\">\n\n\n<div id=\"history-slide-block_0cf67ecc8834adbfcb6dfe775d532fc7\" class=\"module history-slide-block block-has-img\" block-data-decade=\"2010\">\n\t<div class=\"history-slide-block-top\">\n\t\t\t\t<figure>\n\t\t\t<img decoding=\"async\" src=\"https:\/\/www.zinpro.com\/wp-content\/uploads\/2023\/07\/BrandBrochureCover-768x489-1.jpeg\" alt=\"\" \/>\n\t\t<\/figure>\n\t\t\t\t<span class=\"year\">2015<\/span>\n\t<\/div>\n\t<div class=\"history-slide-block-bottom\">\n\t\t<p>Cuatro nuevas aplicaciones lanzan Zinpro a la era de los dispositivos inteligentes: Zinpro\u00ae Equine App\u2122, Zinpro\u00ae DD Check App\u2122, Zinpro FirstStep App y Zinpro Step-Up App.<\/p>\n\t<\/div>\n<\/div>\n\n<\/div><\/div>\n\n<div class=\"swiper-slide wp-block-eedee-block-gutenslide is-position-top-center ed-bg-none\" style=\"--slide-min-width:80%;\" data-hash=\"\"><div class=\"eedee-background-div no-media-background\"><div class=\"eedee-background-div__overlay\" style=\"opacity:1;\"><\/div><\/div><div class=\"slide-content\">\n\n\n<div id=\"history-slide-block_fb8b4576690b6047ae47a2a61ccb8a4e\" class=\"module history-slide-block block-has-img\" block-data-decade=\"2010\">\n\t<div class=\"history-slide-block-top\">\n\t\t\t\t<figure>\n\t\t\t<img decoding=\"async\" src=\"https:\/\/www.zinpro.com\/wp-content\/uploads\/2023\/07\/OurHistory-AvailaCr-440x280-1.jpeg\" alt=\"\" \/>\n\t\t<\/figure>\n\t\t\t\t<span class=\"year\">2016<\/span>\n\t<\/div>\n\t<div class=\"history-slide-block-bottom\">\n\t\t<p>Zinpro\u00ae Availa\u00ae Cr se lanza en China, ampliando la presencia internacional de la empresa tras el lanzamiento de Zinpro\u00ae Availa\u00ae Plus en Europa el a\u00f1o anterior. <\/p>\n\t<\/div>\n<\/div>\n\n<\/div><\/div>\n\n<div class=\"swiper-slide wp-block-eedee-block-gutenslide is-position-top-center ed-bg-none\" style=\"--slide-min-width:80%;\" data-hash=\"\"><div class=\"eedee-background-div no-media-background\"><div class=\"eedee-background-div__overlay\" style=\"opacity:1;\"><\/div><\/div><div class=\"slide-content\">\n\n\n<div id=\"history-slide-block_1b2397c660270f245c513fbbcf0591e5\" class=\"module history-slide-block block-has-img\" block-data-decade=\"2010\">\n\t<div class=\"history-slide-block-top\">\n\t\t\t\t<figure>\n\t\t\t<img decoding=\"async\" src=\"https:\/\/www.zinpro.com\/wp-content\/uploads\/2023\/07\/OurHistory-WilliamScrimgeour-440x513-1.jpeg\" alt=\"William Scrimgeour\" \/>\n\t\t<\/figure>\n\t\t\t\t<span class=\"year\">2017<\/span>\n\t<\/div>\n\t<div class=\"history-slide-block-bottom\">\n\t\t<p>William Scrimgeour pasa a ser Presidente y Consejero Delegado, y Rob Sheffer, Director de Operaciones.<\/p>\n\t<\/div>\n<\/div>\n\n<\/div><\/div>\n\n<div class=\"swiper-slide wp-block-eedee-block-gutenslide is-position-top-center ed-bg-none\" style=\"--slide-min-width:80%;\" data-hash=\"\"><div class=\"eedee-background-div no-media-background\"><div class=\"eedee-background-div__overlay\" style=\"opacity:1;\"><\/div><\/div><div class=\"slide-content\">\n\n\n<div id=\"history-slide-block_902d06aa541c3d380a688ee8396ac684\" class=\"module history-slide-block block-has-img\" block-data-decade=\"2010\">\n\t<div class=\"history-slide-block-top\">\n\t\t\t\t<figure>\n\t\t\t<img decoding=\"async\" src=\"https:\/\/www.zinpro.com\/wp-content\/uploads\/2023\/07\/OurHistory-ProPathProducts-440x280-1.jpeg\" alt=\"\" \/>\n\t\t<\/figure>\n\t\t\t\t<span class=\"year\">2018<\/span>\n\t<\/div>\n\t<div class=\"history-slide-block-bottom\">\n\t\t<p>Se anuncia Zinpro\u00ae ProPath\u00ae - El Zinpro Performance Mineral m\u00e1s vers\u00e1til y sostenible para todas las especies hasta la fecha.<\/p>\n<p>Se abre la oficina regional de la Federaci\u00f3n Rusa. <\/p>\n\t<\/div>\n<\/div>\n\n<\/div><\/div>\n\n<div class=\"swiper-slide wp-block-eedee-block-gutenslide is-position-top-center ed-bg-none\" style=\"--slide-min-width:80%;\" data-hash=\"\"><div class=\"eedee-background-div no-media-background\"><div class=\"eedee-background-div__overlay\" style=\"opacity:1;\"><\/div><\/div><div class=\"slide-content\">\n\n\n<div id=\"history-slide-block_423d93e94b03430f6185c4d14fba0a57\" class=\"module history-slide-block block-has-img\" block-data-decade=\"2010\">\n\t<div class=\"history-slide-block-top\">\n\t\t\t\t<figure>\n\t\t\t<img decoding=\"async\" src=\"https:\/\/www.zinpro.com\/wp-content\/uploads\/2023\/07\/OurHistory-250Review-440x280-1.jpeg\" alt=\"\" \/>\n\t\t<\/figure>\n\t\t\t\t<span class=\"year\">2019<\/span>\n\t<\/div>\n\t<div class=\"history-slide-block-bottom\">\n\t\t<p>Zinpro supera las 250 publicaciones de investigaci\u00f3n revisadas por expertos en m\u00faltiples especies.<\/p>\n\t<\/div>\n<\/div>\n\n<\/div><\/div>\n\n<div class=\"swiper-slide wp-block-eedee-block-gutenslide is-position-top-center ed-bg-none\" style=\"--slide-min-width:80%;\" data-hash=\"\"><div class=\"eedee-background-div no-media-background\"><div class=\"eedee-background-div__overlay\" style=\"opacity:1;\"><\/div><\/div><div class=\"slide-content\">\n\n\n<div id=\"history-slide-block_1e685945fefe7243e7035c81d0c53915\" class=\"module history-slide-block block-has-img\" block-data-decade=\"2020\">\n\t<div class=\"history-slide-block-top\">\n\t\t\t\t<figure>\n\t\t\t<img decoding=\"async\" src=\"https:\/\/www.zinpro.com\/wp-content\/uploads\/2023\/07\/OurHistory-RobSheffer-440x513-1.jpeg\" alt=\"\" \/>\n\t\t<\/figure>\n\t\t\t\t<span class=\"year\">2020<\/span>\n\t<\/div>\n\t<div class=\"history-slide-block-bottom\">\n\t\t<p>Rob Sheffer se convierte en Presidente y Director General tras la jubilaci\u00f3n de William Scrimgeour.<\/p>\n\t<\/div>\n<\/div>\n\n<\/div><\/div>\n\n<div class=\"swiper-slide wp-block-eedee-block-gutenslide is-position-top-center ed-bg-none\" style=\"--slide-min-width:80%;\" data-hash=\"\"><div class=\"eedee-background-div no-media-background\"><div class=\"eedee-background-div__overlay\" style=\"opacity:1;\"><\/div><\/div><div class=\"slide-content\">\n\n\n<div id=\"history-slide-block_49aef896c0c500db1c315455ac4cb2cb\" class=\"module history-slide-block block-has-img\" block-data-decade=\"2020\">\n\t<div class=\"history-slide-block-top\">\n\t\t\t\t<figure>\n\t\t\t<img decoding=\"async\" src=\"https:\/\/www.zinpro.com\/wp-content\/uploads\/2023\/07\/OurHistory-BlueBox-440x280-1.jpeg\" alt=\"\" \/>\n\t\t<\/figure>\n\t\t\t\t<span class=\"year\">2020<\/span>\n\t<\/div>\n\t<div class=\"history-slide-block-bottom\">\n\t\t<p>Zinpro lanza dos herramientas globales, Zinpro\u00ae BlueBox\u2122 y Zinpro\u00ae Perfect Carcass\u00ae, ambas dise\u00f1adas para ayudar a los productores av\u00edcolas a aumentar y maximizar su producci\u00f3n y rentabilidad.<\/p>\n\t<\/div>\n<\/div>\n\n<\/div><\/div>\n\n<div class=\"swiper-slide wp-block-eedee-block-gutenslide is-position-top-center ed-bg-none\" style=\"--slide-min-width:80%;\" data-hash=\"\"><div class=\"eedee-background-div no-media-background\"><div class=\"eedee-background-div__overlay\" style=\"opacity:1;\"><\/div><\/div><div class=\"slide-content\">\n\n\n<div id=\"history-slide-block_562c546c80d492bde218cf4e34dbaec6\" class=\"module history-slide-block block-has-img\" block-data-decade=\"2020\">\n\t<div class=\"history-slide-block-top\">\n\t\t\t\t<figure>\n\t\t\t<img decoding=\"async\" src=\"https:\/\/www.zinpro.com\/wp-content\/uploads\/2023\/07\/OurHistory-MendDefend-440x513-2.jpeg\" alt=\"\" \/>\n\t\t<\/figure>\n\t\t\t\t<span class=\"year\">2020<\/span>\n\t<\/div>\n\t<div class=\"history-slide-block-bottom\">\n\t\t<p>Elemend\u00ae Health LLC, filial de Zinpro Corp., lanza Mend + Defend\u00ae, una l\u00ednea de suplementos nutricionales humanos de primera calidad con oligoelementos, calostro y probi\u00f3ticos.<\/p>\n\t<\/div>\n<\/div>\n\n<\/div><\/div>\n\n<div class=\"swiper-slide wp-block-eedee-block-gutenslide is-position-top-center ed-bg-none\" style=\"--slide-min-width:80%;\" data-hash=\"\"><div class=\"eedee-background-div no-media-background\"><div class=\"eedee-background-div__overlay\" style=\"opacity:1;\"><\/div><\/div><div class=\"slide-content\">\n\n\n<div id=\"history-slide-block_0b126bd10d4a7adaaf0e3a1585f1dcc0\" class=\"module history-slide-block block-has-img\" block-data-decade=\"2020\">\n\t<div class=\"history-slide-block-top\">\n\t\t\t\t<figure>\n\t\t\t<img decoding=\"async\" src=\"https:\/\/www.zinpro.com\/wp-content\/uploads\/2023\/07\/OurHistory_NewBrand.png\" alt=\"\" \/>\n\t\t<\/figure>\n\t\t\t\t<span class=\"year\">2021<\/span>\n\t<\/div>\n\t<div class=\"history-slide-block-bottom\">\n\t\t<p>Zinpro lanza un audaz cambio de marca que representa su pasi\u00f3n y compromiso con el futuro: Zinpro\u00ae Advancing Performance Together\u2122.<\/p>\n\t<\/div>\n<\/div>\n\n<\/div><\/div>\n\n<div class=\"swiper-slide wp-block-eedee-block-gutenslide is-position-top-center ed-bg-none\" style=\"--slide-min-width:80%;\" data-hash=\"\"><div class=\"eedee-background-div no-media-background\"><div class=\"eedee-background-div__overlay\" style=\"opacity:1;\"><\/div><\/div><div class=\"slide-content\">\n\n\n<div id=\"history-slide-block_b16e638993089b15464a54780da8bb34\" class=\"module history-slide-block block-has-img\" block-data-decade=\"2020\">\n\t<div class=\"history-slide-block-top\">\n\t\t\t\t<figure>\n\t\t\t<img decoding=\"async\" src=\"https:\/\/www.zinpro.com\/wp-content\/uploads\/2023\/07\/50YearAnniversaryWithTag-1.jpeg\" alt=\"\" \/>\n\t\t<\/figure>\n\t\t\t\t<span class=\"year\">2021<\/span>\n\t<\/div>\n\t<div class=\"history-slide-block-bottom\">\n\t\t<p>18 de mayo de 2021 - Zinpro celebra 50 a\u00f1os de actividad.<\/p>\n\t<\/div>\n<\/div>\n\n<\/div><\/div>\n\n<div class=\"swiper-slide wp-block-eedee-block-gutenslide is-position-top-center ed-bg-none\" style=\"--slide-min-width:80%;\" data-hash=\"\"><div class=\"eedee-background-div no-media-background\"><div class=\"eedee-background-div__overlay\" style=\"opacity:1;\"><\/div><\/div><div class=\"slide-content\">\n\n\n<div id=\"history-slide-block_e9e587856980611b17bd0c95cb840a0b\" class=\"module history-slide-block block-has-img\" block-data-decade=\"2020\">\n\t<div class=\"history-slide-block-top\">\n\t\t\t\t<figure>\n\t\t\t<img decoding=\"async\" src=\"https:\/\/www.zinpro.com\/wp-content\/uploads\/2023\/07\/OurHistory-70Countries-440x513-1.jpeg\" alt=\"\" \/>\n\t\t<\/figure>\n\t\t\t\t<span class=\"year\">2021<\/span>\n\t<\/div>\n\t<div class=\"history-slide-block-bottom\">\n\t\t<p>Con 11 oficinas en todo el mundo y productos en m\u00e1s de 70 pa\u00edses, Zinpro sigue mejorando la salud y el bienestar de los animales y las personas por un mundo mejor y m\u00e1s sostenible.<\/p>\n\t<\/div>\n<\/div>\n\n<\/div><\/div>\n<\/div><\/div><button class=\"eedee-gutenslider-nav eedee-gutenslider-prev\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 24 24\" width=\"24\" height=\"24\"><circle class=\"bg\" cx=\"13\" cy=\"12\" r=\"11\" \/><path fill=\"none\" d=\"M0 0h24v24H0z\"\/><path class=\"arrow\" d=\"M10.828 12l4.95 4.95-1.414 1.414L8 12l6.364-6.364 1.414 1.414z\"\/><\/svg><\/button><button class=\"eedee-gutenslider-nav eedee-gutenslider-next\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 24 24\" width=\"24\" height=\"24\"><circle class=\"bg\" cx=\"11\" cy=\"12\" r=\"11\" \/><path fill=\"none\" d=\"M0 0h24v24H0z\"\/><path class=\"arrow\" d=\"M13.172 12l-4.95-4.95 1.414-1.414L16 12l-6.364 6.364-1.414-1.414z\"\/><\/svg><\/button><div class=\"eedee-gutenslider-pagination\"><\/div><div class=\"gutenslider-divider-bottom\" style=\"color:#fff;\"><\/div><\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-group alignfull has-background is-layout-constrained wp-block-group-is-layout-constrained\" style=\"background-color:#f7f7f7\">\n<div class=\"wp-block-cover is-light wow fadeInUp\"><img loading=\"lazy\" decoding=\"async\" width=\"1436\" height=\"576\" class=\"wp-block-cover__image-background wp-image-48101\" alt=\"\" src=\"http:\/\/www.zinpro.com\/wp-content\/uploads\/2023\/04\/AboutUs_Experts_-e1673479153231.jpg\" data-object-fit=\"cover\" srcset=\"https:\/\/www.zinpro.com\/wp-content\/uploads\/2023\/04\/AboutUs_Experts_-e1673479153231.jpg 1436w, https:\/\/www.zinpro.com\/wp-content\/uploads\/2023\/04\/AboutUs_Experts_-e1673479153231-300x120.jpg 300w, https:\/\/www.zinpro.com\/wp-content\/uploads\/2023\/04\/AboutUs_Experts_-e1673479153231-1024x411.jpg 1024w, https:\/\/www.zinpro.com\/wp-content\/uploads\/2023\/04\/AboutUs_Experts_-e1673479153231-18x7.jpg 18w\" sizes=\"auto, (max-width: 1436px) 100vw, 1436px\" \/><span aria-hidden=\"true\" class=\"wp-block-cover__background has-background-dim-30 has-background-dim\"><\/span><div class=\"wp-block-cover__inner-container is-layout-flow wp-block-cover-is-layout-flow\">\n<h1 class=\"wp-block-heading has-white-color has-text-color\" id=\"h-get-connected-with-an-expert\">Con\u00e9ctate <br>con un experto<\/h1>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-group is-layout-constrained wp-container-core-group-is-layout-90ba889e wp-block-group-is-layout-constrained\">\n\n<div id=\"resp-spacer-block_39fb5f51a6c1dd56ceb2433486b2812d\" class=\"zinpro-spacer-block\"><\/div>\n\n<style>\n#resp-spacer-block_39fb5f51a6c1dd56ceb2433486b2812d {\n\tmargin-top: 60px;\n}\n\n@media screen and (max-width: 1366px) {\n\t#resp-spacer-block_39fb5f51a6c1dd56ceb2433486b2812d {\n\t\tmargin-top: 40px;\n\t}\n}\n\n@media screen and (max-width: 960px) {\n\t#resp-spacer-block_39fb5f51a6c1dd56ceb2433486b2812d {\n\t\tmargin-top: 20px;\n\t}\n}\n<\/style>\n\n\n<h6 class=\"wp-block-heading wow fadeInUp\" id=\"h-learn-more-about-how-the-culture-commitment-and-science-at-zinpro-can-help-your-business\">Descubra c\u00f3mo podemos contribuir al futuro de su negocio poni\u00e9ndose en contacto hoy mismo con uno de nuestros representantes.<\/h6>\n\n\n\n<div class=\"wp-block-buttons wow fadeInUp is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\" id=\"wow-fadeInUp\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/www.zinpro.com\/es_es\/lets-connect\/\">Contacte con nosotros<\/a><\/div>\n<\/div>\n<\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Our History<\/p>\n<p>Celebrating 50 Years of Innovation<\/p>\n<p>2021 marks our 50th anniversary&nbsp;and we are&nbsp;proud to celebrate 50 years of setting the bar for nutritional health solutions, services [&#8230;]<\/p>\n","protected":false},"author":8,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_tec_requires_first_save":true,"_eb_attr":"","_uag_custom_page_level_css":"","_EventAllDay":false,"_EventTimezone":"","_EventStartDate":"","_EventEndDate":"","_EventStartDateUTC":"","_EventEndDateUTC":"","_EventShowMap":false,"_EventShowMapLink":false,"_EventURL":"","_EventCost":"","_EventCostDescription":"","_EventCurrencySymbol":"","_EventCurrencyCode":"","_EventCurrencyPosition":"","_EventDateTimeSeparator":"","_EventTimeRangeSeparator":"","_EventOrganizerID":[],"_EventVenueID":[],"_OrganizerEmail":"","_OrganizerPhone":"","_OrganizerWebsite":"","_VenueAddress":"","_VenueCity":"","_VenueCountry":"","_VenueProvince":"","_VenueState":"","_VenueZip":"","_VenuePhone":"","_VenueURL":"","_VenueStateProvince":"","_VenueLat":"","_VenueLng":"","_VenueShowMap":false,"_VenueShowMapLink":false,"_tribe_blocks_recurrence_rules":"","_tribe_blocks_recurrence_description":"","_tribe_blocks_recurrence_exclusions":"","_ecp_custom_2":"","footnotes":""},"class_list":["post-55641","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Our History &#8211; Zinpro\u00ae<\/title>\n<meta name=\"description\" content=\"Read more about Our History and from Zinpro\u00ae here.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.zinpro.com\/es_es\/our-history\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Our History &#8211; Zinpro\u00ae\" \/>\n<meta property=\"og:description\" content=\"Read more about Our History and from Zinpro\u00ae here.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.zinpro.com\/es_es\/our-history\/\" \/>\n<meta property=\"og:site_name\" content=\"Zinpro\u00ae\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ZinproCorp\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-26T14:14:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.zinpro.com\/wp-content\/uploads\/2023\/06\/History-Hero.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"448\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@wdolezal\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.zinpro.com\\\/our-history\\\/\",\"url\":\"https:\\\/\\\/www.zinpro.com\\\/our-history\\\/\",\"name\":\"Our History &#8211; Zinpro\u00ae\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.zinpro.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.zinpro.com\\\/our-history\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.zinpro.com\\\/our-history\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.zinpro.com\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/History-Hero.jpg\",\"datePublished\":\"2023-06-08T17:50:33+00:00\",\"dateModified\":\"2025-08-26T14:14:06+00:00\",\"description\":\"Read more about Our History and from Zinpro\u00ae here.\",\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.zinpro.com\\\/our-history\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.zinpro.com\\\/our-history\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.zinpro.com\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/History-Hero.jpg\",\"contentUrl\":\"https:\\\/\\\/www.zinpro.com\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/History-Hero.jpg\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.zinpro.com\\\/#website\",\"url\":\"https:\\\/\\\/www.zinpro.com\\\/\",\"name\":\"Zinpro\u00ae\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.zinpro.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Nuestra historia - Zinpro","description":"Lea m\u00e1s sobre Nuestra historia y de Zinpro\u00ae aqu\u00ed.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.zinpro.com\/es_es\/our-history\/","og_locale":"es_ES","og_type":"article","og_title":"Our History &#8211; Zinpro\u00ae","og_description":"Read more about Our History and from Zinpro\u00ae here.","og_url":"https:\/\/www.zinpro.com\/es_es\/our-history\/","og_site_name":"Zinpro\u00ae","article_publisher":"https:\/\/www.facebook.com\/ZinproCorp\/","article_modified_time":"2025-08-26T14:14:06+00:00","og_image":[{"width":1280,"height":448,"url":"https:\/\/www.zinpro.com\/wp-content\/uploads\/2023\/06\/History-Hero.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@wdolezal","twitter_misc":{"Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.zinpro.com\/our-history\/","url":"https:\/\/www.zinpro.com\/our-history\/","name":"Nuestra historia - Zinpro","isPartOf":{"@id":"https:\/\/www.zinpro.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.zinpro.com\/our-history\/#primaryimage"},"image":{"@id":"https:\/\/www.zinpro.com\/our-history\/#primaryimage"},"thumbnailUrl":"https:\/\/www.zinpro.com\/wp-content\/uploads\/2023\/06\/History-Hero.jpg","datePublished":"2023-06-08T17:50:33+00:00","dateModified":"2025-08-26T14:14:06+00:00","description":"Lea m\u00e1s sobre Nuestra historia y de Zinpro\u00ae aqu\u00ed.","inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.zinpro.com\/our-history\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.zinpro.com\/our-history\/#primaryimage","url":"https:\/\/www.zinpro.com\/wp-content\/uploads\/2023\/06\/History-Hero.jpg","contentUrl":"https:\/\/www.zinpro.com\/wp-content\/uploads\/2023\/06\/History-Hero.jpg"},{"@type":"WebSite","@id":"https:\/\/www.zinpro.com\/#website","url":"https:\/\/www.zinpro.com\/","name":"Zinpro","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.zinpro.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"spectra_custom_meta":{"_edit_lock":["1756217648:8"],"_oembed_708cc253cdbaa4bc8081a8ef9ffff158":["<iframe title=\"Zinpro Brand Video\" width=\"640\" height=\"360\" src=\"https:\/\/www.youtube.com\/embed\/XWkNHeZiOGE?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe>"],"_oembed_time_708cc253cdbaa4bc8081a8ef9ffff158":["1686246746"],"_edit_last":["8"],"_yoast_wpseo_content_score":["90"],"_yoast_wpseo_estimated-reading-time-minutes":["2"],"_yoast_wpseo_wordproof_timestamp":[""],"ss_social_share_disable":[""],"_oembed_03f0620d6769bca305e5366784f05595":["<iframe title=\"Zinpro 50th Anniversary Video\" width=\"640\" height=\"360\" src=\"https:\/\/www.youtube.com\/embed\/fdo0xyEW20g?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe>"],"_oembed_time_03f0620d6769bca305e5366784f05595":["1689006710"],"_yoast_wpseo_focuskeywords":["[]"],"_yoast_wpseo_keywordsynonyms":["[\"\"]"],"_uag_custom_page_level_css":[""],"_EventAllDay":[""],"_EventTimezone":[""],"_EventStartDate":[""],"_EventEndDate":[""],"_EventStartDateUTC":[""],"_EventEndDateUTC":[""],"_EventShowMap":[""],"_EventShowMapLink":[""],"_EventURL":[""],"_EventCost":[""],"_EventCostDescription":[""],"_EventCurrencySymbol":[""],"_EventCurrencyCode":[""],"_EventCurrencyPosition":[""],"_EventDateTimeSeparator":[""],"_EventTimeRangeSeparator":[""],"_OrganizerEmail":[""],"_OrganizerPhone":[""],"_OrganizerWebsite":[""],"_VenueAddress":[""],"_VenueCity":[""],"_VenueCountry":[""],"_VenueProvince":[""],"_VenueState":[""],"_VenueZip":[""],"_VenuePhone":[""],"_VenueURL":[""],"_VenueStateProvince":[""],"_VenueLat":[""],"_VenueLng":[""],"_VenueShowMap":[""],"_VenueShowMapLink":[""],"_tribe_blocks_recurrence_rules":[""],"_tribe_blocks_recurrence_exclusions":[""],"_ecp_custom_2":[""],"footnotes":[""],"_eb_reusable_block_ids":["a:0:{}"],"_uag_css_file_name":["uag-css-55641.css"],"_uagb_previous_block_counts":["a:90:{s:21:\"uagb\/advanced-heading\";i:0;s:15:\"uagb\/blockquote\";i:0;s:12:\"uagb\/buttons\";i:0;s:18:\"uagb\/buttons-child\";i:0;s:19:\"uagb\/call-to-action\";i:0;s:15:\"uagb\/cf7-styler\";i:0;s:11:\"uagb\/column\";i:0;s:12:\"uagb\/columns\";i:0;s:14:\"uagb\/container\";i:0;s:21:\"uagb\/content-timeline\";i:0;s:27:\"uagb\/content-timeline-child\";i:0;s:14:\"uagb\/countdown\";i:0;s:12:\"uagb\/counter\";i:0;s:8:\"uagb\/faq\";i:0;s:14:\"uagb\/faq-child\";i:0;s:10:\"uagb\/forms\";i:0;s:17:\"uagb\/forms-accept\";i:0;s:19:\"uagb\/forms-checkbox\";i:0;s:15:\"uagb\/forms-date\";i:0;s:16:\"uagb\/forms-email\";i:0;s:17:\"uagb\/forms-hidden\";i:0;s:15:\"uagb\/forms-name\";i:0;s:16:\"uagb\/forms-phone\";i:0;s:16:\"uagb\/forms-radio\";i:0;s:17:\"uagb\/forms-select\";i:0;s:19:\"uagb\/forms-textarea\";i:0;s:17:\"uagb\/forms-toggle\";i:0;s:14:\"uagb\/forms-url\";i:0;s:14:\"uagb\/gf-styler\";i:0;s:15:\"uagb\/google-map\";i:0;s:11:\"uagb\/how-to\";i:0;s:16:\"uagb\/how-to-step\";i:0;s:9:\"uagb\/icon\";i:0;s:14:\"uagb\/icon-list\";i:0;s:20:\"uagb\/icon-list-child\";i:0;s:10:\"uagb\/image\";i:0;s:18:\"uagb\/image-gallery\";i:0;s:13:\"uagb\/info-box\";i:0;s:18:\"uagb\/inline-notice\";i:0;s:11:\"uagb\/lottie\";i:0;s:21:\"uagb\/marketing-button\";i:0;s:10:\"uagb\/modal\";i:0;s:18:\"uagb\/popup-builder\";i:0;s:16:\"uagb\/post-button\";i:0;s:18:\"uagb\/post-carousel\";i:0;s:17:\"uagb\/post-excerpt\";i:0;s:14:\"uagb\/post-grid\";i:0;s:15:\"uagb\/post-image\";i:0;s:17:\"uagb\/post-masonry\";i:0;s:14:\"uagb\/post-meta\";i:0;s:18:\"uagb\/post-taxonomy\";i:0;s:18:\"uagb\/post-timeline\";i:0;s:15:\"uagb\/post-title\";i:0;s:20:\"uagb\/restaurant-menu\";i:0;s:26:\"uagb\/restaurant-menu-child\";i:0;s:11:\"uagb\/review\";i:0;s:12:\"uagb\/section\";i:0;s:14:\"uagb\/separator\";i:0;s:11:\"uagb\/slider\";i:0;s:17:\"uagb\/slider-child\";i:0;s:17:\"uagb\/social-share\";i:0;s:23:\"uagb\/social-share-child\";i:0;s:16:\"uagb\/star-rating\";i:0;s:23:\"uagb\/sure-cart-checkout\";i:0;s:22:\"uagb\/sure-cart-product\";i:0;s:15:\"uagb\/sure-forms\";i:0;s:22:\"uagb\/table-of-contents\";i:0;s:9:\"uagb\/tabs\";i:0;s:15:\"uagb\/tabs-child\";i:0;s:18:\"uagb\/taxonomy-list\";i:0;s:9:\"uagb\/team\";i:0;s:16:\"uagb\/testimonial\";i:0;s:14:\"uagb\/wp-search\";i:0;s:19:\"uagb\/instagram-feed\";i:0;s:10:\"uagb\/login\";i:0;s:17:\"uagb\/loop-builder\";i:0;s:18:\"uagb\/loop-category\";i:0;s:20:\"uagb\/loop-pagination\";i:0;s:15:\"uagb\/loop-reset\";i:0;s:16:\"uagb\/loop-search\";i:0;s:14:\"uagb\/loop-sort\";i:0;s:17:\"uagb\/loop-wrapper\";i:0;s:13:\"uagb\/register\";i:0;s:19:\"uagb\/register-email\";i:0;s:24:\"uagb\/register-first-name\";i:0;s:23:\"uagb\/register-last-name\";i:0;s:22:\"uagb\/register-password\";i:0;s:30:\"uagb\/register-reenter-password\";i:0;s:19:\"uagb\/register-terms\";i:0;s:22:\"uagb\/register-username\";i:0;}"],"_uag_page_assets":["a:9:{s:3:\"css\";s:260:\".uag-blocks-common-selector{z-index:var(--z-index-desktop) !important}@media(max-width: 976px){.uag-blocks-common-selector{z-index:var(--z-index-tablet) !important}}@media(max-width: 767px){.uag-blocks-common-selector{z-index:var(--z-index-mobile) !important}}\";s:2:\"js\";s:0:\"\";s:18:\"current_block_list\";a:22:{i:0;s:10:\"core\/group\";i:1;s:10:\"core\/cover\";i:2;s:12:\"core\/heading\";i:3;s:14:\"core\/paragraph\";i:5;s:12:\"core\/columns\";i:6;s:11:\"core\/column\";i:7;s:12:\"core\/buttons\";i:8;s:11:\"core\/button\";i:10;s:12:\"epyt\/youtube\";i:11;s:23:\"eedee\/block-gutenslider\";i:12;s:22:\"eedee\/block-gutenslide\";i:13;s:20:\"zinpro\/history-slide\";i:15;s:24:\"zinpro\/responsive-spacer\";i:16;s:11:\"core\/search\";i:17;s:17:\"core\/latest-posts\";i:18;s:20:\"core\/latest-comments\";i:19;s:13:\"core\/archives\";i:20;s:15:\"core\/categories\";i:21;s:17:\"core\/social-links\";i:22;s:16:\"core\/social-link\";i:23;s:11:\"core\/spacer\";i:24;s:10:\"core\/image\";}s:8:\"uag_flag\";b:0;s:11:\"uag_version\";s:10:\"1778614166\";s:6:\"gfonts\";a:0:{}s:10:\"gfonts_url\";s:0:\"\";s:12:\"gfonts_files\";a:0:{}s:14:\"uag_faq_layout\";b:0;}"]},"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"gs-tiny":false,"xl":false,"xxl":false,"xxxl":false,"xxxxl":false,"xxxxxl":false,"1536x1536":false,"2048x2048":false,"trp-custom-language-flag":false,"gform-image-choice-sm":false,"gform-image-choice-md":false,"gform-image-choice-lg":false,"menu-24x24":false,"menu-36x36":false,"menu-48x48":false},"uagb_author_info":{"display_name":"Matt Wolleat","author_link":"https:\/\/www.zinpro.com\/es_es\/resource-center\/author\/mwolleatzinpro-com\/"},"uagb_comment_info":0,"uagb_excerpt":"Our History Celebrating 50 Years of Innovation 2021 marks our 50th anniversary&nbsp;and we are&nbsp;proud to celebrate 50 years of setting the bar for nutritional health solutions, services [...]","_links":{"self":[{"href":"https:\/\/www.zinpro.com\/es_es\/wp-json\/wp\/v2\/pages\/55641","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.zinpro.com\/es_es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.zinpro.com\/es_es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.zinpro.com\/es_es\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.zinpro.com\/es_es\/wp-json\/wp\/v2\/comments?post=55641"}],"version-history":[{"count":0,"href":"https:\/\/www.zinpro.com\/es_es\/wp-json\/wp\/v2\/pages\/55641\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.zinpro.com\/es_es\/wp-json\/wp\/v2\/media?parent=55641"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}